{"id":9,"date":"2023-12-02T06:55:45","date_gmt":"2023-12-02T06:55:45","guid":{"rendered":"https:\/\/texclean-lqej15w7kl.live-website.com\/?page_id=9"},"modified":"2025-05-13T09:43:50","modified_gmt":"2025-05-13T09:43:50","slug":"textilreinigung-waescherei-kiel","status":"publish","type":"page","link":"https:\/\/texclean-sh.de\/en\/","title":{"rendered":"Home"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9\" class=\"elementor elementor-9\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-84b637f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"16590\" data-id=\"84b637f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-00552b1\" data-eae-slider=\"26606\" data-id=\"00552b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-inner-section elementor-element elementor-element-3ecfb9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"60551\" data-id=\"3ecfb9e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-15c1a1e\" data-eae-slider=\"19666\" data-id=\"15c1a1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef35b9d elementor-widget elementor-widget-image\" data-id=\"ef35b9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/texclean-sh.de\/wp-content\/uploads\/2025\/05\/Untitled-1.jpg\" class=\"attachment-large size-large wp-image-2091\" alt=\"\" srcset=\"https:\/\/texclean-sh.de\/wp-content\/uploads\/2025\/05\/Untitled-1.jpg 1024w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2025\/05\/Untitled-1-300x300.jpg 300w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2025\/05\/Untitled-1-150x150.jpg 150w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2025\/05\/Untitled-1-768x768.jpg 768w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2025\/05\/Untitled-1-12x12.jpg 12w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2025\/05\/Untitled-1-600x600.jpg 600w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2025\/05\/Untitled-1-100x100.jpg 100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1fd1102\" data-eae-slider=\"89680\" data-id=\"1fd1102\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e60d4f8 elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"e60d4f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Dein mobiler W\u00e4scheservice in Kiel &amp; Umgebung<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e757543 elementor-widget elementor-widget-heading\" data-id=\"e757543\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">abholen - reinigen &amp; b\u00fcgeln - liefern<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d68cb1b elementor-widget-mobile__width-initial elementor-widget elementor-widget-shortcode\" data-id=\"d68cb1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\r\n<div class=\"zipcodetext\"><\/div>\r\n\r\n<form name=\"zipredirect\" id=\"zipredirect\" action=\"\" >\r\n\r\n<input type=\"text\" \r\n       id=\"ziptext\" \r\n       name=\"zipredirector\" \r\n       maxlength=\"5\" \r\n       placeholder=\"Postleitzahl\" \r\n       title=\"\" >\r\n       <input type=\"submit\" value=\"\">\r\n       \r\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form> \r\n\r\n<div class=\"zipcodetext\" id=\"zipredirectshow\"><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35ef5a1 elementor-widget-mobile__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"35ef5a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-grow\" href=\"https:\/\/api.whatsapp.com\/send?phone=4917687735658\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0465de elementor-widget elementor-widget-heading\" data-id=\"e0465de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Mehr Infos<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-7692ac7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"76020\" data-id=\"7692ac7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f90e539\" data-eae-slider=\"94539\" data-id=\"f90e539\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-inner-section elementor-element elementor-element-2947bb3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"85777\" data-id=\"2947bb3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-00ef769\" data-eae-slider=\"29407\" data-id=\"00ef769\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25156e9 elementor-widget elementor-widget-heading\" data-id=\"25156e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wir reinigen Smart<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-466121b elementor-widget elementor-widget-heading\" data-id=\"466121b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mobile Textilreinigung &amp; W\u00e4scherei in Kiel &amp; Umgebung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-inner-section elementor-element elementor-element-c2915e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"51634\" data-id=\"c2915e8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1b54e29\" data-eae-slider=\"8845\" data-id=\"1b54e29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-241810c elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"241810c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"512\" viewbox=\"0 0 384 383.999986\" height=\"512\" preserveaspectratio=\"xMidYMid meet\"><defs><clippath id=\"79d8597c63\"><path d=\"M 132.035156 10.421875 L 383.910156 10.421875 L 383.910156 373.421875 L 132.035156 373.421875 Z M 132.035156 10.421875 \" clip-rule=\"nonzero\"><\/path><\/clippath><\/defs><path fill=\"#000000\" d=\"M 103.207031 338.882812 C 90.269531 329.4375 78.789062 318.246094 69.164062 305.8125 C 59.535156 293.386719 51.761719 279.722656 46.097656 265.394531 C 34.726562 236.75 32.058594 205.460938 37.722656 176.332031 L 37.972656 174.972656 C 38.058594 174.511719 38.132812 174.0625 38.242188 173.609375 L 38.863281 170.910156 L 39.484375 168.214844 L 39.636719 167.542969 C 39.691406 167.316406 39.757812 167.097656 39.820312 166.871094 L 40.1875 165.539062 L 40.917969 162.882812 L 41.46875 160.890625 L 41.683594 160.234375 L 43.371094 155.007812 C 45.789062 148.089844 48.65625 141.382812 51.949219 134.925781 L 53.21875 132.523438 L 53.847656 131.320312 L 54.160156 130.722656 C 54.261719 130.519531 54.386719 130.332031 54.496094 130.136719 L 57.222656 125.457031 C 57.4375 125.058594 57.691406 124.6875 57.9375 124.308594 L 58.664062 123.171875 L 60.121094 120.890625 L 60.84375 119.753906 C 61.09375 119.382812 61.363281 119.023438 61.617188 118.648438 L 63.164062 116.445312 C 67.316406 110.589844 71.847656 105.050781 76.710938 99.863281 L 55.398438 82.597656 L 104.019531 121.800781 L 101.226562 29.421875 L 10.253906 46.195312 L 36.640625 67.464844 C 31.105469 75.183594 26.128906 83.246094 21.730469 91.578125 L 20.105469 94.71875 C 19.835938 95.246094 19.554688 95.765625 19.296875 96.289062 L 18.542969 97.890625 L 17.046875 101.089844 L 16.300781 102.6875 C 16.050781 103.222656 15.792969 103.75 15.574219 104.300781 L 12.859375 110.800781 C 12.746094 111.074219 12.632812 111.335938 12.527344 111.613281 L 12.222656 112.441406 L 11.609375 114.09375 L 10.394531 117.390625 C 7.261719 126.21875 4.75 135.230469 2.871094 144.332031 L 1.613281 151.183594 L 1.453125 152.035156 L 1.332031 152.898438 L 1.09375 154.613281 L 0.609375 158.054688 L 0.375 159.769531 C 0.339844 160.058594 0.292969 160.34375 0.261719 160.632812 L 0.179688 161.496094 L -0.148438 164.945312 L -0.472656 168.390625 C -0.539062 168.960938 -0.558594 169.535156 -0.589844 170.113281 L -0.859375 175.28125 C -0.90625 176.429688 -0.988281 177.578125 -0.980469 178.730469 L -1.023438 185.613281 C -1.042969 186.183594 -1.003906 186.757812 -0.992188 187.324219 L -0.933594 189.046875 L -0.804688 192.46875 C -0.75 194.753906 -0.550781 197.03125 -0.394531 199.304688 C -0.308594 200.441406 -0.179688 201.578125 -0.0742188 202.707031 C 0.0351562 203.84375 0.136719 204.972656 0.285156 206.105469 L 0.707031 209.496094 C 0.859375 210.625 1.039062 211.75 1.203125 212.875 L 1.453125 214.554688 L 1.742188 216.238281 L 2.332031 219.585938 C 2.785156 221.816406 3.195312 224.046875 3.726562 226.253906 C 7.707031 243.933594 14.179688 260.917969 22.84375 276.5 C 31.488281 292.09375 42.285156 306.304688 54.714844 318.648438 C 67.148438 331.003906 81.210938 341.492188 96.320312 349.765625 C 111.425781 358.042969 127.582031 364.117188 144.121094 367.75 C 160.65625 371.398438 177.558594 372.632812 194.148438 371.574219 C 177.554688 370.488281 161.261719 367.109375 145.910156 361.5625 C 130.546875 356.03125 116.148438 348.328125 103.207031 338.882812 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><g clip-path=\"url(#79d8597c63)\"><path fill=\"#000000\" d=\"M 369.40625 123.066406 C 360.113281 101.105469 346.800781 81.375 329.847656 64.441406 C 312.898438 47.507812 293.152344 34.207031 271.167969 24.921875 C 248.410156 15.296875 224.230469 10.417969 199.304688 10.417969 C 178.089844 10.417969 157.28125 13.984375 137.464844 21.023438 C 133.441406 22.453125 131.335938 26.875 132.765625 30.894531 C 134.199219 34.914062 138.621094 37.015625 142.644531 35.585938 C 160.792969 29.140625 179.859375 25.875 199.304688 25.875 C 222.144531 25.875 244.300781 30.339844 265.144531 39.148438 C 285.28125 47.660156 303.375 59.847656 318.914062 75.367188 C 334.445312 90.890625 346.644531 108.960938 355.164062 129.085938 C 363.980469 149.910156 368.453125 172.046875 368.453125 194.855469 C 368.453125 214.046875 365.261719 232.875 358.96875 250.8125 C 352.878906 268.144531 344.023438 284.304688 332.648438 298.84375 C 321.378906 313.242188 307.945312 325.664062 292.71875 335.761719 C 277.253906 346.019531 260.339844 353.601562 242.445312 358.304688 C 238.3125 359.386719 235.847656 363.613281 236.929688 367.738281 C 237.847656 371.207031 240.980469 373.5 244.410156 373.5 C 245.058594 373.5 245.71875 373.417969 246.378906 373.242188 C 265.914062 368.117188 284.382812 359.832031 301.273438 348.632812 C 317.886719 337.621094 332.539062 324.070312 344.832031 308.363281 C 357.25 292.496094 366.910156 274.851562 373.558594 255.925781 C 380.433594 236.339844 383.917969 215.792969 383.917969 194.855469 C 383.917969 169.960938 379.039062 145.804688 369.40625 123.066406 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#000000\" d=\"M 199.304688 79.972656 C 202.871094 79.972656 205.75 77.089844 205.75 73.53125 L 205.75 50.476562 C 205.75 46.921875 202.871094 44.035156 199.304688 44.035156 C 195.746094 44.035156 192.867188 46.921875 192.867188 50.476562 L 192.867188 73.53125 C 192.867188 77.089844 195.746094 79.972656 199.304688 79.972656 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 134.453125 92.617188 C 135.652344 94.683594 137.816406 95.835938 140.042969 95.835938 C 141.140625 95.835938 142.246094 95.5625 143.261719 94.976562 C 146.34375 93.199219 147.402344 89.257812 145.621094 86.179688 L 134.082031 66.214844 C 132.300781 63.132812 128.359375 62.078125 125.277344 63.855469 C 122.195312 65.632812 121.136719 69.574219 122.914062 72.652344 L 134.453125 92.617188 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 99.875 127.171875 L 79.890625 115.644531 C 76.800781 113.867188 72.863281 114.917969 71.085938 118.003906 C 69.304688 121.082031 70.363281 125.015625 73.445312 126.792969 L 93.429688 138.320312 C 94.445312 138.90625 95.550781 139.183594 96.644531 139.183594 C 98.871094 139.183594 101.035156 138.035156 102.230469 135.964844 C 104.007812 132.882812 102.957031 128.949219 99.875 127.171875 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 87.210938 191.960938 C 87.210938 188.40625 84.332031 185.523438 80.769531 185.523438 L 57.691406 185.523438 C 54.132812 185.523438 51.246094 188.40625 51.246094 191.960938 C 51.246094 195.515625 54.132812 198.402344 57.691406 198.402344 L 80.769531 198.402344 C 84.332031 198.402344 87.210938 195.515625 87.210938 191.960938 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 76.675781 269.140625 C 77.761719 269.140625 78.871094 268.863281 79.890625 268.277344 L 99.875 256.75 C 102.957031 254.972656 104.007812 251.03125 102.230469 247.953125 C 100.449219 244.875 96.511719 243.816406 93.429688 245.59375 L 73.445312 257.125 C 70.363281 258.90625 69.304688 262.839844 71.085938 265.921875 C 72.277344 267.984375 74.441406 269.140625 76.675781 269.140625 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 125.277344 320.0625 C 126.292969 320.648438 127.398438 320.929688 128.492188 320.929688 C 130.71875 320.929688 132.890625 319.773438 134.082031 317.710938 L 145.621094 297.742188 C 147.402344 294.660156 146.34375 290.722656 143.261719 288.945312 C 140.179688 287.167969 136.234375 288.226562 134.453125 291.304688 L 122.914062 311.269531 C 121.136719 314.347656 122.195312 318.289062 125.277344 320.0625 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 199.304688 303.949219 C 195.746094 303.949219 192.867188 306.828125 192.867188 310.390625 L 192.867188 333.441406 C 192.867188 337.003906 195.746094 339.878906 199.304688 339.878906 C 202.871094 339.878906 205.75 337.003906 205.75 333.441406 L 205.75 310.390625 C 205.75 306.828125 202.871094 303.949219 199.304688 303.949219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 252.996094 297.742188 L 264.535156 317.710938 C 265.726562 319.773438 267.898438 320.929688 270.121094 320.929688 C 271.21875 320.929688 272.324219 320.648438 273.339844 320.0625 C 276.421875 318.289062 277.472656 314.347656 275.695312 311.269531 L 264.160156 291.304688 C 262.382812 288.21875 258.4375 287.167969 255.355469 288.945312 C 252.273438 290.722656 251.214844 294.660156 252.996094 297.742188 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 305.1875 245.59375 C 302.105469 243.816406 298.167969 244.875 296.386719 247.953125 C 294.609375 251.03125 295.660156 254.972656 298.742188 256.75 L 318.730469 268.277344 C 319.746094 268.863281 320.851562 269.140625 321.941406 269.140625 C 324.171875 269.140625 326.339844 267.984375 327.53125 265.921875 C 329.308594 262.839844 328.253906 258.90625 325.175781 257.125 L 305.1875 245.59375 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 347.367188 191.960938 C 347.367188 188.40625 344.480469 185.523438 340.921875 185.523438 L 317.84375 185.523438 C 314.292969 185.523438 311.398438 188.40625 311.398438 191.960938 C 311.398438 195.515625 314.292969 198.402344 317.84375 198.402344 L 340.921875 198.402344 C 344.480469 198.402344 347.367188 195.515625 347.367188 191.960938 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 318.730469 115.644531 L 298.742188 127.171875 C 295.660156 128.949219 294.609375 132.882812 296.386719 135.964844 C 297.578125 138.035156 299.742188 139.183594 301.96875 139.183594 C 303.066406 139.183594 304.171875 138.90625 305.1875 138.320312 L 325.175781 126.792969 C 328.253906 125.015625 329.308594 121.082031 327.53125 118.003906 C 325.75 114.921875 321.8125 113.867188 318.730469 115.644531 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 273.339844 63.855469 C 270.257812 62.078125 266.3125 63.132812 264.535156 66.214844 L 252.996094 86.179688 C 251.214844 89.257812 252.273438 93.199219 255.355469 94.976562 C 256.371094 95.5625 257.476562 95.835938 258.570312 95.835938 C 260.796875 95.835938 262.960938 94.683594 264.160156 92.617188 L 275.695312 72.652344 C 277.472656 69.574219 276.421875 65.632812 273.339844 63.855469 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 284.335938 198.902344 L 284.335938 178.363281 C 284.335938 170.097656 281.265625 165.019531 274.066406 165.019531 C 269.546875 165.019531 266.324219 167.328125 263.84375 169.589844 L 264.28125 163.597656 L 264.28125 152.183594 L 254.472656 152.183594 L 254.472656 198.902344 L 264.28125 198.902344 L 264.28125 176.585938 C 266.441406 174.511719 267.945312 173.371094 270.410156 173.371094 C 273.246094 173.371094 274.527344 174.855469 274.527344 179.621094 L 274.527344 198.902344 L 284.335938 198.902344 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 148.921875 201.808594 L 158.394531 186.066406 C 160.445312 181.953125 162.484375 177.957031 164.300781 173.882812 L 164.761719 173.882812 C 164.535156 178.464844 164.117188 185.453125 164.117188 190.035156 L 164.117188 201.808594 Z M 159.261719 159.625 L 132.90625 202.984375 L 132.90625 214.535156 L 164.117188 214.535156 L 164.117188 231.738281 L 179.699219 231.738281 L 179.699219 214.535156 L 188.027344 214.535156 L 188.027344 201.808594 L 179.699219 201.808594 L 179.699219 159.625 L 159.261719 159.625 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 221.007812 221.5 C 214.921875 221.5 209.871094 217.75 209.871094 211.433594 C 209.871094 206.953125 212.21875 202.84375 215.40625 199.984375 C 224.46875 203.777344 230.625 206.183594 230.625 212.5625 C 230.625 218.574219 226.484375 221.5 221.007812 221.5 Z M 220.816406 169.863281 C 226.320312 169.863281 229.574219 173.574219 229.574219 179.167969 C 229.574219 182.949219 227.996094 186.421875 225.148438 189.773438 C 217.808594 186.847656 212.789062 184.03125 212.789062 178.179688 C 212.789062 172.625 216.390625 169.863281 220.816406 169.863281 Z M 246.15625 213.125 C 246.15625 203.550781 240.59375 198.027344 233.707031 194.265625 L 233.707031 193.8125 C 238.644531 190.496094 243.136719 184.910156 243.136719 178.050781 C 243.136719 166.0625 234.40625 158.261719 221.191406 158.261719 C 207.78125 158.261719 198.09375 165.90625 198.09375 178.179688 C 198.09375 185.71875 202.203125 190.976562 207.804688 195.132812 L 207.804688 195.589844 C 200.988281 199.226562 195.464844 204.621094 195.464844 213.300781 C 195.464844 225.03125 206.226562 233.101562 220.628906 233.101562 C 235.925781 233.101562 246.15625 224.511719 246.15625 213.125 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTextilpflege in nur 48h\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBei TexClean Textilreinigung in kiel und Umgebung garantieren wir eine schnelle Reinigung \u2013 im Durchschnitt dauert es nur 48 Stunden, bis wir deine Kleidung frisch gereinigt zu dir nach Hause liefern. Sollte es einmal l\u00e4nger dauern, informieren wir dich umgehend.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e90a8fb elementor-widget elementor-widget-spacer\" data-id=\"e90a8fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c0f36ef\" data-eae-slider=\"29419\" data-id=\"c0f36ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa7bdda elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"fa7bdda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"512\" viewbox=\"0 0 384 383.999986\" height=\"512\" preserveaspectratio=\"xMidYMid meet\"><defs><clippath id=\"5dfe04be91\"><path d=\"M 3 4 L 382.5 4 L 382.5 384 L 3 384 Z M 3 4 \" clip-rule=\"nonzero\"><\/path><\/clippath><\/defs><g clip-path=\"url(#5dfe04be91)\"><path fill=\"#000000\" d=\"M 39.101562 283.441406 C 40.742188 286.273438 39.800781 289.902344 36.96875 291.550781 C 36.023438 292.097656 35.011719 292.355469 34 292.355469 C 31.972656 292.355469 29.980469 291.296875 28.859375 289.40625 C 8.519531 254.425781 -0.0078125 214.605469 4.253906 174.257812 C 9.53125 123.871094 34.136719 78.566406 73.527344 46.691406 C 112.882812 14.816406 162.304688 0.183594 212.707031 5.480469 C 246.46875 9.039062 278.242188 21.390625 305.292969 41.375 L 301.203125 26.972656 C 300.292969 23.828125 302.113281 20.542969 305.257812 19.644531 C 308.402344 18.75 311.691406 20.574219 312.597656 23.722656 L 321.894531 56.320312 C 322.382812 58.070312 322.070312 59.957031 320.988281 61.429688 C 319.902344 62.90625 318.226562 63.804688 316.40625 63.867188 L 282.539062 65.082031 C 282.46875 65.085938 282.398438 65.089844 282.332031 65.089844 C 279.148438 65.089844 276.492188 62.574219 276.390625 59.375 C 276.285156 56.101562 278.835938 53.355469 282.085938 53.234375 L 300.472656 52.578125 C 274.640625 32.867188 244.058594 20.703125 211.449219 17.273438 C 164.226562 12.300781 117.882812 26.023438 80.972656 55.90625 C 44.0625 85.789062 20.996094 128.261719 16.03125 175.5 C 12.050781 213.328125 20.019531 250.65625 39.101562 283.441406 Z M 382.5 195.378906 L 382.5 192.457031 C 382.261719 159.566406 373.527344 127.558594 356.8125 98.820312 C 355.167969 95.988281 351.535156 95.03125 348.703125 96.679688 C 345.871094 98.328125 344.929688 101.957031 346.570312 104.785156 C 365.65625 137.570312 373.625 174.894531 369.640625 212.730469 C 359.398438 310.238281 271.738281 381.222656 174.222656 370.953125 C 141.648438 367.519531 111.03125 355.355469 85.203125 335.652344 L 103.585938 334.992188 C 106.835938 334.871094 109.390625 332.125 109.285156 328.847656 C 109.179688 325.585938 106.453125 323.019531 103.132812 323.144531 L 69.265625 324.359375 C 67.449219 324.425781 65.769531 325.320312 64.6875 326.796875 C 63.605469 328.273438 63.289062 330.152344 63.777344 331.910156 L 73.074219 364.503906 C 73.84375 367.113281 76.222656 368.8125 78.773438 368.8125 C 79.332031 368.8125 79.890625 368.734375 80.414062 368.582031 C 83.558594 367.683594 85.378906 364.402344 84.503906 361.25 L 80.378906 346.855469 C 107.433594 366.832031 139.203125 379.191406 172.964844 382.738281 C 179.746094 383.460938 186.492188 383.804688 193.203125 383.804688 C 236.4375 383.804688 278.066406 369.136719 312.144531 341.535156 C 351.535156 309.65625 376.140625 264.355469 381.453125 213.96875 C 382.105469 207.753906 382.453125 201.550781 382.5 195.378906 Z M 110.988281 249.082031 C 110.988281 249.082031 121.089844 230.183594 121.125 230.175781 C 123.574219 225.546875 121.78125 219.527344 117.136719 217.0625 C 112.488281 214.574219 106.523438 216.386719 104.035156 221.03125 L 93.9375 239.90625 C 91.410156 244.621094 93.203125 250.503906 97.886719 253.019531 C 102.609375 255.535156 108.464844 253.769531 110.988281 249.082031 Z M 56.0625 179.527344 C 65.394531 183.738281 82.773438 191.570312 85.957031 192.800781 C 93.9375 195.894531 96.167969 203.253906 97.449219 209.496094 C 104.179688 203.191406 114.425781 201.535156 122.988281 206.117188 C 128.148438 208.871094 131.953125 213.507812 133.675781 219.167969 C 134.039062 220.351562 134.296875 221.542969 134.441406 222.738281 C 139.417969 221.792969 144.46875 222.554688 148.96875 224.949219 C 154.128906 227.703125 157.933594 232.34375 159.65625 238.003906 C 159.691406 238.144531 159.730469 238.285156 159.765625 238.421875 C 159.914062 238.386719 160.023438 238.339844 160.167969 238.296875 C 165.839844 236.585938 171.804688 237.167969 177 239.945312 C 182.160156 242.699219 185.964844 247.339844 187.6875 253 C 187.722656 253.144531 187.761719 253.277344 187.796875 253.421875 C 187.941406 253.378906 188.050781 253.332031 188.199219 253.296875 C 193.871094 251.578125 199.835938 252.160156 205.03125 254.941406 C 207.519531 256.265625 209.679688 258.035156 211.472656 260.148438 L 235.476562 273.425781 C 240.160156 276.003906 246.089844 274.289062 248.648438 269.613281 C 251.210938 264.972656 249.453125 259.054688 244.769531 256.414062 L 210.847656 237.3125 C 207.847656 235.632812 206.785156 231.851562 208.46875 228.867188 C 210.152344 225.878906 213.921875 224.816406 216.921875 226.503906 L 259.847656 250.488281 C 264.53125 253.0625 270.421875 251.347656 273.019531 246.671875 C 275.542969 242.03125 273.824219 236.113281 269.140625 233.472656 C 268.996094 233.398438 235.21875 214.285156 235.21875 214.285156 C 232.21875 212.597656 231.15625 208.808594 232.839844 205.828125 C 234.523438 202.84375 238.332031 201.789062 241.332031 203.476562 L 280.703125 225.742188 C 282.898438 226.972656 285.460938 227.257812 287.914062 226.558594 C 290.476562 225.832031 292.5625 224.175781 293.804688 221.882812 C 296.367188 217.273438 294.609375 211.347656 289.925781 208.675781 L 234.925781 177.339844 C 225.777344 172.113281 214.179688 176.800781 200.785156 182.226562 C 190.613281 186.347656 179.195312 190.964844 167.632812 190.96875 C 155.8125 190.96875 143.847656 186.132812 132.832031 170.980469 C 131.808594 169.554688 131.441406 167.757812 131.808594 166.03125 C 132.175781 164.308594 133.234375 162.828125 134.773438 161.949219 C 151.054688 152.625 164.742188 142.417969 175.425781 131.613281 C 177.953125 129.058594 180.511719 126.683594 183.074219 124.5 C 171.511719 119.613281 161.558594 121.960938 151.128906 124.417969 C 140.554688 126.917969 129.613281 129.507812 118.339844 123.28125 L 87.640625 109.117188 L 54.816406 178.96875 C 55.21875 179.148438 55.621094 179.332031 56.0625 179.527344 Z M 197.675781 128.914062 C 193.210938 132 188.710938 135.847656 184.246094 140.34375 C 174.183594 150.503906 161.78125 160.121094 147.25 168.988281 C 162.070312 184.523438 177.953125 178.078125 196.140625 170.726562 C 206.019531 166.726562 216.121094 162.636719 225.964844 162.636719 C 231.085938 162.636719 236.171875 163.746094 241.074219 166.558594 L 296.074219 197.894531 C 298.417969 199.226562 300.394531 200.925781 302.078125 202.878906 L 331.203125 190.460938 L 302.773438 117.175781 L 280.960938 128.855469 C 269.324219 134.902344 258.347656 130.414062 247.734375 126.078125 C 233.539062 120.273438 218.863281 114.269531 197.675781 128.914062 Z M 224.9375 281.796875 L 224.828125 281.734375 L 216.523438 277.167969 C 216.195312 279.828125 215.386719 282.425781 214.105469 284.851562 L 208.691406 294.96875 L 215.609375 298.785156 C 220.292969 301.359375 226.21875 299.648438 228.78125 294.960938 C 231.339844 290.300781 229.621094 284.386719 224.9375 281.796875 Z M 193.46875 297.09375 C 193.46875 297.09375 203.128906 279.019531 203.128906 278.996094 C 205.617188 274.414062 203.789062 268.335938 199.175781 265.886719 C 194.53125 263.410156 188.527344 265.226562 186.078125 269.855469 L 176.378906 287.953125 C 173.855469 292.671875 175.648438 298.554688 180.367188 301.074219 C 185.050781 303.59375 190.941406 301.8125 193.46875 297.09375 Z M 164.046875 284.691406 C 164.046875 284.691406 175.097656 264.015625 175.097656 264 C 177.585938 259.386719 175.757812 253.359375 171.144531 250.890625 C 166.5 248.414062 160.5 250.222656 158.007812 254.863281 L 146.957031 275.542969 C 144.46875 280.261719 146.226562 286.140625 150.945312 288.660156 C 155.558594 291.140625 161.597656 289.3125 164.046875 284.691406 Z M 133.417969 274.582031 C 133.417969 274.582031 147.070312 249.027344 147.070312 249.015625 C 149.558594 244.378906 147.765625 238.363281 143.117188 235.894531 C 138.507812 233.441406 132.503906 235.226562 130.015625 239.828125 L 116.332031 265.441406 C 113.804688 270.152344 115.597656 276.042969 120.28125 278.5625 C 122.550781 279.769531 125.1875 280.019531 127.675781 279.265625 C 130.164062 278.515625 132.210938 276.847656 133.417969 274.582031 Z M 133.417969 274.582031 \" fill-opacity=\"1\" fill-rule=\"evenodd\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tF\u00fcr Privat- &amp; Gesch\u00e4ftskunden\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTexClean Mobile Textilreinigung &amp; W\u00e4scherei in Kiel &amp; Umgebung  ist der perfekte Partner sowohl f\u00fcr private als auch f\u00fcr Gesch\u00e4ftskunden. Unser umfangreiches Know-how in der Reinigung von Uniformen, Arbeitskleidung oder allt\u00e4glicher Garderobe macht uns zur ersten Wahl f\u00fcr jede Art von Textil.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-958bb4a elementor-widget elementor-widget-spacer\" data-id=\"958bb4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-fd36b35\" data-eae-slider=\"20774\" data-id=\"fd36b35\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38d7e48 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"38d7e48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"512\" viewbox=\"0 0 384 383.999986\" height=\"512\" preserveaspectratio=\"xMidYMid meet\"><defs><clippath id=\"29f2f6a5b7\"><path d=\"M 265.214844 112.703125 L 348.289062 112.703125 L 348.289062 268.578125 L 265.214844 268.578125 Z M 265.214844 112.703125 \" clip-rule=\"nonzero\"><\/path><\/clippath><clippath id=\"2e07e4dcbe\"><path d=\"M 268 62.421875 L 317 62.421875 L 317 111 L 268 111 Z M 268 62.421875 \" clip-rule=\"nonzero\"><\/path><\/clippath><\/defs><g clip-path=\"url(#29f2f6a5b7)\"><path fill=\"#2e2d2c\" d=\"M 323.933594 206.402344 C 323.21875 203.195312 321.386719 200.335938 318.777344 198.347656 L 297.265625 181.929688 C 296.082031 181.027344 294.394531 181.253906 293.492188 182.433594 C 292.589844 183.613281 292.816406 185.300781 293.996094 186.203125 L 315.511719 202.621094 C 317.117188 203.847656 318.242188 205.601562 318.679688 207.570312 L 328.769531 252.765625 C 329.796875 257.378906 326.882812 261.964844 322.265625 262.992188 C 321.648438 263.132812 321.015625 263.203125 320.390625 263.203125 C 316.414062 263.203125 312.898438 260.382812 312.03125 256.496094 L 302.839844 215.3125 C 302.703125 214.695312 302.355469 214.148438 301.851562 213.765625 L 276.90625 194.609375 C 276.859375 194.566406 276.808594 194.523438 276.753906 194.480469 C 273.929688 192.316406 270.632812 188.089844 270.632812 183.3125 L 270.632812 131.800781 C 270.632812 124.296875 276.742188 118.1875 284.25 118.1875 C 289.644531 118.1875 294.5625 121.542969 297.082031 126.9375 C 297.09375 126.957031 297.101562 126.976562 297.109375 126.996094 C 297.128906 127.046875 297.152344 127.101562 297.175781 127.15625 L 308.394531 151.691406 C 308.828125 152.636719 309.761719 153.246094 310.800781 153.261719 L 336.671875 153.691406 C 336.707031 153.691406 336.742188 153.691406 336.773438 153.691406 C 340.195312 153.800781 342.933594 156.671875 342.875 160.09375 C 342.820312 163.535156 340.003906 166.292969 336.574219 166.292969 C 336.535156 166.292969 336.503906 166.292969 336.464844 166.292969 L 304.914062 165.773438 C 304.882812 165.773438 304.851562 165.769531 304.820312 165.769531 C 302.410156 165.695312 300.285156 164.285156 299.285156 162.09375 L 287.535156 136.335938 C 286.917969 134.984375 285.320312 134.386719 283.972656 135.003906 C 282.617188 135.621094 282.019531 137.214844 282.636719 138.566406 L 294.390625 164.324219 C 295.296875 166.308594 296.734375 167.992188 298.550781 169.199219 C 300.363281 170.402344 302.472656 171.074219 304.644531 171.144531 C 304.707031 171.148438 304.769531 171.148438 304.828125 171.148438 L 336.378906 171.667969 C 336.445312 171.671875 336.507812 171.671875 336.574219 171.671875 C 342.925781 171.671875 348.148438 166.558594 348.257812 160.183594 C 348.308594 157.097656 347.160156 154.164062 345.027344 151.929688 C 342.898438 149.699219 340.027344 148.414062 336.941406 148.316406 C 336.882812 148.316406 336.824219 148.3125 336.761719 148.3125 L 312.585938 147.914062 L 302.070312 124.917969 C 302.058594 124.894531 302.046875 124.867188 302.03125 124.84375 C 302.011719 124.78125 301.984375 124.722656 301.957031 124.664062 C 300.363281 121.25 297.957031 118.339844 294.996094 116.253906 C 291.800781 114 288.085938 112.8125 284.25 112.8125 C 273.773438 112.8125 265.25 121.328125 265.25 131.800781 L 265.25 183.3125 C 265.25 186.246094 266.109375 189.304688 267.734375 192.15625 C 269.140625 194.625 271.054688 196.84375 273.277344 198.589844 C 273.335938 198.644531 273.398438 198.695312 273.460938 198.746094 L 297.800781 217.433594 L 306.78125 257.667969 C 307.476562 260.78125 309.234375 263.582031 311.730469 265.558594 C 314.191406 267.507812 317.269531 268.578125 320.390625 268.578125 C 321.410156 268.578125 322.4375 268.464844 323.4375 268.242188 C 330.949219 266.566406 335.695312 259.101562 334.019531 251.597656 L 323.933594 206.402344 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#2e2d2c\" d=\"M 284.488281 216.65625 C 283.070312 216.207031 281.558594 216.992188 281.109375 218.410156 L 279.164062 224.578125 C 278.535156 226.515625 277.226562 228.167969 275.488281 229.234375 L 237.734375 252.359375 C 236.382812 253.1875 234.835938 253.625 233.265625 253.625 C 230.25 253.625 227.515625 252.09375 225.945312 249.53125 C 224.746094 247.582031 224.382812 245.28125 224.914062 243.054688 C 225.449219 240.832031 226.820312 238.945312 228.773438 237.75 L 262.980469 216.796875 C 263.53125 216.460938 263.941406 215.941406 264.136719 215.328125 L 267.230469 205.6875 C 267.683594 204.273438 266.90625 202.757812 265.492188 202.304688 C 264.078125 201.851562 262.5625 202.628906 262.105469 204.042969 L 259.316406 212.734375 L 225.960938 233.167969 C 222.78125 235.113281 220.554688 238.179688 219.683594 241.800781 C 218.8125 245.421875 219.40625 249.167969 221.355469 252.34375 C 222.625 254.414062 224.417969 256.121094 226.539062 257.28125 C 228.59375 258.40625 230.917969 259.003906 233.265625 259.003906 C 235.828125 259.003906 238.347656 258.289062 240.542969 256.945312 L 278.300781 233.820312 C 281.136719 232.082031 283.261719 229.386719 284.285156 226.222656 C 284.289062 226.21875 284.289062 226.210938 284.292969 226.207031 L 286.242188 220.027344 C 286.691406 218.613281 285.902344 217.101562 284.488281 216.65625 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><g clip-path=\"url(#2e07e4dcbe)\"><path fill=\"#2e2d2c\" d=\"M 292.351562 67.898438 C 302.523438 67.898438 310.800781 76.167969 310.800781 86.335938 C 310.800781 96.503906 302.523438 104.773438 292.351562 104.773438 C 282.175781 104.773438 273.898438 96.503906 273.898438 86.335938 C 273.898438 76.167969 282.175781 67.898438 292.351562 67.898438 Z M 292.351562 110.152344 C 298.714844 110.152344 304.699219 107.671875 309.199219 103.175781 C 313.703125 98.675781 316.183594 92.695312 316.183594 86.335938 C 316.183594 79.976562 313.703125 73.996094 309.199219 69.496094 C 304.699219 65 298.714844 62.519531 292.351562 62.519531 C 285.984375 62.519531 280 65 275.5 69.496094 C 271 73.996094 268.515625 79.976562 268.515625 86.335938 C 268.515625 92.695312 271 98.675781 275.5 103.175781 C 280 107.671875 285.984375 110.152344 292.351562 110.152344 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#2e2d2c\" d=\"M 381.308594 112.816406 L 320.882812 112.816406 C 320.167969 112.816406 319.484375 113.097656 318.980469 113.605469 C 318.476562 114.109375 318.191406 114.792969 318.191406 115.507812 L 318.214844 134.179688 C 318.214844 135.664062 319.417969 136.867188 320.90625 136.867188 C 320.90625 136.867188 320.90625 136.867188 320.910156 136.867188 C 322.394531 136.863281 323.597656 135.660156 323.597656 134.175781 L 323.578125 118.191406 L 378.621094 118.191406 L 378.621094 181.929688 L 323.585938 181.929688 L 323.597656 180.367188 C 323.605469 178.882812 322.40625 177.671875 320.921875 177.664062 C 320.914062 177.664062 320.910156 177.664062 320.90625 177.664062 C 319.425781 177.664062 318.222656 178.859375 318.214844 180.339844 L 318.191406 184.601562 C 318.191406 185.320312 318.472656 186.003906 318.976562 186.511719 C 319.480469 187.019531 320.167969 187.304688 320.882812 187.304688 L 381.308594 187.304688 C 382.796875 187.304688 384 186.101562 384 184.617188 L 384 115.503906 C 384 114.019531 382.796875 112.816406 381.308594 112.816406 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#2e2d2c\" d=\"M 356.535156 132.351562 C 358.019531 132.351562 359.226562 131.148438 359.226562 129.664062 C 359.226562 128.179688 358.019531 126.976562 356.535156 126.976562 L 345.59375 126.976562 C 344.105469 126.976562 342.902344 128.179688 342.902344 129.664062 C 342.902344 131.148438 344.105469 132.351562 345.59375 132.351562 L 356.535156 132.351562 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#2e2d2c\" d=\"M 34.007812 134.480469 C 35.15625 133.648438 36.507812 133.210938 37.910156 133.210938 C 38.269531 133.210938 38.632812 133.238281 38.988281 133.296875 C 40.753906 133.578125 42.300781 134.53125 43.347656 135.980469 L 76.683594 181.648438 C 77.1875 182.34375 78 182.757812 78.855469 182.757812 C 79.171875 182.757812 79.476562 182.703125 79.773438 182.59375 C 80.003906 182.511719 80.222656 182.394531 80.421875 182.25 C 81.621094 181.386719 81.890625 179.707031 81.023438 178.511719 L 47.695312 132.851562 L 47.6875 132.84375 C 45.800781 130.238281 43.015625 128.523438 39.839844 128.011719 C 39.195312 127.910156 38.546875 127.855469 37.902344 127.855469 C 35.371094 127.855469 32.9375 128.648438 30.867188 130.140625 C 28.261719 132.027344 26.542969 134.8125 26.035156 137.988281 C 25.53125 141.113281 26.257812 144.25 28.082031 146.832031 L 28.082031 146.835938 L 72.980469 208.484375 C 73.484375 209.175781 74.292969 209.589844 75.152344 209.589844 C 75.464844 209.589844 75.773438 209.535156 76.066406 209.429688 C 76.296875 209.347656 76.515625 209.230469 76.71875 209.082031 C 77.296875 208.664062 77.679688 208.046875 77.792969 207.339844 C 77.90625 206.636719 77.738281 205.925781 77.320312 205.347656 L 32.507812 143.820312 L 32.503906 143.8125 C 31.457031 142.367188 31.035156 140.597656 31.320312 138.835938 C 31.605469 137.074219 32.558594 135.527344 34.007812 134.480469 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#2e2d2c\" d=\"M 160.878906 206 C 160.367188 200.980469 159.570312 195.824219 156.996094 192.019531 C 152.660156 185.601562 128.863281 153.089844 126.164062 149.402344 L 126.160156 149.390625 C 124.140625 146.621094 120.878906 144.964844 117.4375 144.964844 C 115.164062 144.964844 112.984375 145.667969 111.140625 147 C 110.261719 147.636719 109.488281 148.394531 108.839844 149.257812 C 107.953125 150.4375 108.191406 152.117188 109.371094 153.003906 C 109.839844 153.355469 110.394531 153.539062 110.976562 153.539062 C 111.828125 153.539062 112.609375 153.152344 113.121094 152.472656 C 113.445312 152.039062 113.835938 151.65625 114.28125 151.335938 C 115.207031 150.667969 116.300781 150.3125 117.441406 150.3125 C 119.171875 150.3125 120.808594 151.144531 121.824219 152.53125 L 121.835938 152.558594 L 121.851562 152.574219 C 122.425781 153.355469 148.171875 188.519531 152.558594 195.015625 C 154.421875 197.769531 155.003906 202.300781 155.570312 206.683594 C 156.015625 210.117188 161.292969 210.023438 160.878906 206 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#2e2d2c\" d=\"M 111.648438 239.785156 C 107.808594 238.621094 103.488281 237.488281 98.902344 236.332031 L 98.886719 236.328125 C 89.210938 233.886719 78.242188 231.121094 73.976562 227.390625 L 55.027344 210.726562 C 54.957031 210.644531 54.890625 210.570312 54.816406 210.503906 C 53.523438 209.269531 52.789062 207.609375 52.746094 205.820312 C 52.707031 204.035156 53.363281 202.339844 54.597656 201.050781 C 55.6875 199.90625 57.152344 199.183594 58.722656 199.019531 C 60.191406 198.863281 61.257812 197.542969 61.101562 196.074219 C 60.957031 194.710938 59.8125 193.683594 58.441406 193.683594 C 58.347656 193.683594 58.25 193.6875 58.15625 193.695312 C 55.328125 193.996094 52.6875 195.296875 50.722656 197.355469 C 48.5 199.679688 47.320312 202.730469 47.394531 205.945312 C 47.464844 208.984375 48.664062 211.855469 50.777344 214.03125 C 50.890625 214.191406 51.027344 214.335938 51.171875 214.464844 L 70.417969 231.390625 L 70.46875 231.441406 L 70.492188 231.453125 C 75.742188 236.011719 86.839844 238.808594 97.574219 241.515625 L 97.582031 241.515625 C 102.097656 242.652344 106.308594 243.894531 110.035156 244.886719 C 113.964844 245.9375 115.445312 240.9375 111.648438 239.785156 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#2e2d2c\" d=\"M 90.675781 156.355469 C 89.902344 157.613281 90.292969 159.261719 91.550781 160.035156 C 91.972656 160.296875 92.457031 160.433594 92.953125 160.433594 C 93.890625 160.433594 94.742188 159.957031 95.234375 159.160156 C 95.695312 158.410156 96.292969 157.769531 97.015625 157.246094 C 98.164062 156.417969 99.511719 155.976562 100.917969 155.976562 C 101.277344 155.976562 101.640625 156.007812 101.996094 156.0625 C 103.761719 156.347656 105.308594 157.300781 106.355469 158.746094 L 108.121094 161.1875 C 108.621094 161.882812 109.433594 162.296875 110.292969 162.296875 C 110.605469 162.296875 110.914062 162.242188 111.207031 162.132812 C 111.4375 162.050781 111.660156 161.933594 111.859375 161.789062 C 113.054688 160.925781 113.324219 159.246094 112.460938 158.054688 L 110.695312 155.613281 C 108.808594 153.007812 106.023438 151.292969 102.84375 150.78125 C 102.203125 150.679688 101.554688 150.625 100.910156 150.625 C 98.378906 150.625 95.945312 151.417969 93.875 152.910156 C 92.582031 153.847656 91.503906 155.003906 90.675781 156.355469 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#2e2d2c\" d=\"M 89.472656 167.371094 L 91.867188 170.679688 C 92.371094 171.371094 93.179688 171.785156 94.039062 171.785156 C 94.351562 171.785156 94.660156 171.730469 94.953125 171.625 C 95.1875 171.539062 95.40625 171.425781 95.605469 171.277344 C 96.1875 170.859375 96.566406 170.242188 96.679688 169.535156 C 96.792969 168.828125 96.625 168.121094 96.207031 167.542969 L 93.8125 164.234375 C 91.554688 161.117188 87.902344 159.253906 84.035156 159.253906 C 81.492188 159.253906 79.058594 160.042969 76.996094 161.53125 C 76.332031 162.007812 75.71875 162.554688 75.171875 163.148438 C 74.6875 163.675781 74.4375 164.359375 74.46875 165.074219 C 74.5 165.789062 74.808594 166.445312 75.332031 166.929688 C 75.828125 167.386719 76.472656 167.636719 77.144531 167.636719 C 77.890625 167.636719 78.609375 167.320312 79.117188 166.769531 C 79.421875 166.4375 79.761719 166.136719 80.132812 165.867188 C 81.277344 165.039062 82.628906 164.601562 84.042969 164.601562 C 86.191406 164.601562 88.21875 165.636719 89.472656 167.371094 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#2e2d2c\" d=\"M 14.335938 84.558594 L 83.640625 84.558594 C 88.582031 84.558594 92.605469 88.574219 92.605469 93.511719 L 92.605469 105.578125 L 5.371094 105.566406 L 5.371094 93.511719 C 5.371094 88.574219 9.394531 84.558594 14.335938 84.558594 Z M 80.621094 249.269531 L 14.335938 249.269531 C 9.394531 249.269531 5.371094 245.25 5.371094 240.3125 L 5.371094 226.730469 L 39.863281 226.738281 C 41.347656 226.738281 42.550781 225.535156 42.550781 224.054688 C 42.550781 222.574219 41.347656 221.371094 39.863281 221.371094 L 5.371094 221.363281 L 5.371094 110.9375 L 92.605469 110.945312 L 92.605469 132.992188 C 92.605469 134.472656 93.804688 135.675781 95.289062 135.675781 C 96.773438 135.675781 97.976562 134.472656 97.976562 132.992188 L 97.976562 93.511719 C 97.976562 85.613281 91.546875 79.1875 83.640625 79.1875 L 14.335938 79.1875 C 6.429688 79.1875 0 85.613281 0 93.511719 L 0 240.3125 C 0 248.210938 6.429688 254.636719 14.335938 254.636719 L 80.621094 254.636719 C 82.105469 254.636719 83.308594 253.4375 83.308594 251.953125 C 83.308594 250.46875 82.105469 249.269531 80.621094 249.269531 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#2e2d2c\" d=\"M 196.292969 181.199219 L 224.230469 160.085938 C 224.917969 159.566406 225.328125 158.742188 225.328125 157.882812 C 225.328125 157.019531 224.917969 156.195312 224.230469 155.679688 L 196.292969 134.5625 C 195.453125 133.925781 194.339844 133.820312 193.398438 134.289062 C 192.453125 134.761719 191.863281 135.707031 191.863281 136.761719 L 191.863281 155.136719 L 170.367188 155.136719 C 168.839844 155.136719 167.601562 156.378906 167.601562 157.898438 C 167.601562 159.421875 168.839844 160.664062 170.367188 160.664062 L 194.433594 160.664062 C 194.460938 160.660156 194.492188 160.660156 194.519531 160.660156 L 194.566406 160.660156 C 194.59375 160.660156 194.625 160.660156 194.652344 160.664062 C 196.164062 160.648438 197.390625 159.414062 197.390625 157.898438 L 197.390625 142.316406 L 217.980469 157.882812 L 192.960938 176.796875 C 192.371094 177.242188 191.992188 177.886719 191.890625 178.617188 C 191.789062 179.351562 191.976562 180.078125 192.421875 180.664062 C 192.949219 181.359375 193.753906 181.761719 194.628906 181.761719 C 195.234375 181.761719 195.8125 181.566406 196.292969 181.199219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t Zuverl\u00e4ssiger Abhol- &amp; Lieferservice\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUnser Hol- und Bringservice macht es dir leicht, Zeit zu sparen. Lass uns deine Kleidung waschen und genie\u00dfe den Komfort, sie termingerecht zu Hause geliefert zu bekommen \u2013 ein Service von TexClean f\u00fcr mehr Bequemlichkeit im Alltag.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-814ec93 elementor-widget elementor-widget-spacer\" data-id=\"814ec93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-inner-section elementor-element elementor-element-631d1a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"18384\" data-id=\"631d1a2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-38befa9\" data-eae-slider=\"61436\" data-id=\"38befa9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81dca10 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"81dca10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"512\" viewbox=\"0 0 384 383.999986\" height=\"512\" preserveaspectratio=\"xMidYMid meet\"><defs><clippath id=\"22550aa6ff\"><path d=\"M 54 0 L 329.863281 0 L 329.863281 384 L 54 384 Z M 54 0 \" clip-rule=\"nonzero\"><\/path><\/clippath><\/defs><path fill=\"#231f20\" d=\"M 154.402344 218.617188 C 166.636719 223.796875 179.628906 226.421875 193.019531 226.421875 C 206.40625 226.421875 219.398438 223.796875 231.632812 218.617188 C 243.445312 213.613281 254.054688 206.457031 263.164062 197.339844 C 272.273438 188.21875 279.425781 177.601562 284.421875 165.777344 C 289.59375 153.53125 292.21875 140.527344 292.21875 127.125 C 292.21875 113.722656 289.59375 100.714844 284.421875 88.472656 C 279.421875 76.648438 272.269531 66.027344 263.164062 56.910156 C 254.054688 47.792969 243.445312 40.632812 231.632812 35.632812 C 219.398438 30.453125 206.40625 27.828125 193.019531 27.828125 C 179.628906 27.828125 166.636719 30.453125 154.402344 35.632812 C 142.589844 40.632812 131.980469 47.792969 122.871094 56.910156 C 113.761719 66.03125 106.609375 76.648438 101.613281 88.472656 C 96.441406 100.714844 93.816406 113.722656 93.816406 127.125 C 93.816406 140.527344 96.441406 153.53125 101.613281 165.777344 C 106.613281 177.601562 113.765625 188.21875 122.871094 197.339844 C 131.980469 206.457031 142.589844 213.617188 154.402344 218.617188 Z M 101.800781 127.125 C 101.800781 114.796875 104.210938 102.835938 108.964844 91.582031 C 113.558594 80.710938 120.136719 70.945312 128.515625 62.558594 C 136.894531 54.171875 146.652344 47.589844 157.511719 42.988281 C 168.753906 38.230469 180.703125 35.816406 193.019531 35.816406 C 205.332031 35.816406 217.28125 38.230469 228.523438 42.988281 C 239.382812 47.589844 249.140625 54.171875 257.519531 62.558594 C 265.898438 70.945312 272.476562 80.710938 277.070312 91.582031 C 281.824219 102.835938 284.234375 114.796875 284.234375 127.125 C 284.234375 139.453125 281.824219 151.410156 277.070312 162.664062 C 272.476562 173.535156 265.898438 183.300781 257.519531 191.6875 C 249.140625 200.074219 239.382812 206.660156 228.523438 211.257812 C 217.28125 216.015625 205.332031 218.429688 193.019531 218.429688 C 180.703125 218.429688 168.753906 216.015625 157.511719 211.257812 C 146.652344 206.660156 136.894531 200.074219 128.515625 191.6875 C 120.136719 183.300781 113.558594 173.535156 108.964844 162.664062 C 104.210938 151.410156 101.800781 139.453125 101.800781 127.125 Z M 101.800781 127.125 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#231f20\" d=\"M 162.742188 170.730469 C 163.453125 171.585938 164.488281 172.105469 165.597656 172.164062 C 165.667969 172.167969 165.738281 172.167969 165.808594 172.167969 C 166.84375 172.167969 167.84375 171.765625 168.589844 171.039062 L 243.269531 98.421875 C 244.851562 96.886719 244.890625 94.355469 243.351562 92.773438 C 241.816406 91.191406 239.289062 91.152344 237.710938 92.691406 L 166.113281 162.304688 L 141.773438 133.089844 C 140.359375 131.394531 137.84375 131.164062 136.148438 132.578125 C 134.457031 133.992188 134.230469 136.511719 135.640625 138.207031 Z M 162.742188 170.730469 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><g clip-path=\"url(#22550aa6ff)\"><path fill=\"#231f20\" d=\"M 329.296875 344.605469 L 279.972656 220.039062 C 281.460938 217.949219 282.558594 215.59375 283.203125 213.0625 L 283.207031 213.042969 C 284.214844 209.101562 287.058594 205.816406 290.808594 204.265625 C 290.8125 204.261719 290.820312 204.257812 290.824219 204.257812 C 294.789062 202.617188 298.113281 199.839844 300.433594 196.230469 C 302.757812 192.617188 303.90625 188.441406 303.757812 184.160156 L 303.757812 184.128906 C 303.613281 180.070312 305.414062 176.125 308.570312 173.578125 C 308.578125 173.570312 308.582031 173.570312 308.585938 173.566406 C 311.929688 170.867188 314.335938 167.261719 315.542969 163.136719 C 316.75 159.011719 316.671875 154.675781 315.3125 150.597656 C 315.3125 150.597656 315.3125 150.59375 315.308594 150.589844 C 314.027344 146.734375 314.644531 142.4375 316.953125 139.101562 L 316.972656 139.074219 C 316.972656 139.074219 316.972656 139.070312 316.972656 139.070312 C 319.414062 135.546875 320.703125 131.414062 320.703125 127.125 C 320.703125 122.835938 319.414062 118.707031 316.96875 115.175781 L 316.957031 115.15625 C 314.644531 111.816406 314.027344 107.523438 315.308594 103.667969 C 315.308594 103.664062 315.3125 103.660156 315.3125 103.652344 C 316.671875 99.574219 316.753906 95.242188 315.542969 91.117188 C 314.335938 86.992188 311.929688 83.382812 308.578125 80.683594 C 305.417969 78.132812 303.617188 74.183594 303.757812 70.113281 L 303.757812 70.101562 C 303.90625 65.808594 302.757812 61.632812 300.433594 58.023438 C 298.113281 54.410156 294.789062 51.636719 290.816406 49.992188 C 287.058594 48.4375 284.214844 45.152344 283.207031 41.203125 L 283.207031 41.191406 C 282.144531 37.035156 279.871094 33.347656 276.632812 30.539062 C 273.390625 27.726562 269.425781 25.992188 265.164062 25.53125 L 265.144531 25.53125 C 261.105469 25.09375 257.460938 22.746094 255.390625 19.25 C 255.386719 19.246094 255.382812 19.242188 255.382812 19.238281 C 253.191406 15.539062 249.972656 12.640625 246.066406 10.855469 C 242.164062 9.066406 237.867188 8.527344 233.644531 9.285156 L 233.625 9.289062 C 229.632812 10.011719 225.472656 8.789062 222.5 6.023438 L 222.480469 6.007812 C 219.339844 3.085938 215.433594 1.21875 211.183594 0.609375 C 206.9375 0.00390625 202.667969 0.699219 198.832031 2.625 C 195.191406 4.449219 190.84375 4.449219 187.203125 2.625 C 183.371094 0.699219 179.097656 0.00390625 174.851562 0.609375 C 170.601562 1.21875 166.695312 3.085938 163.558594 6.003906 L 163.535156 6.023438 C 160.5625 8.789062 156.402344 10.007812 152.414062 9.289062 L 152.394531 9.285156 C 148.171875 8.523438 143.875 9.066406 139.96875 10.855469 C 136.0625 12.640625 132.84375 15.539062 130.660156 19.230469 C 130.65625 19.234375 130.652344 19.238281 130.652344 19.242188 C 128.582031 22.738281 124.933594 25.089844 120.898438 25.527344 L 120.871094 25.53125 C 116.609375 25.996094 112.644531 27.726562 109.40625 30.539062 C 106.164062 33.347656 103.890625 37.035156 102.828125 41.199219 L 102.828125 41.207031 C 101.820312 45.152344 98.976562 48.433594 95.21875 49.988281 C 95.214844 49.992188 95.199219 49.996094 95.195312 49.996094 C 91.238281 51.640625 87.917969 54.414062 85.597656 58.019531 C 83.277344 61.632812 82.128906 65.808594 82.277344 70.101562 L 82.277344 70.121094 C 82.421875 74.183594 80.617188 78.128906 77.449219 80.6875 C 74.105469 83.382812 71.699219 86.988281 70.492188 91.113281 C 69.285156 95.238281 69.363281 99.574219 70.722656 103.652344 C 72.007812 107.511719 71.394531 111.8125 69.082031 115.152344 L 69.0625 115.179688 C 66.621094 118.707031 65.332031 122.835938 65.332031 127.125 C 65.332031 131.414062 66.621094 135.542969 69.0625 139.070312 L 69.078125 139.09375 C 71.394531 142.4375 72.007812 146.738281 70.722656 150.597656 C 69.363281 154.675781 69.28125 159.011719 70.492188 163.136719 C 71.699219 167.261719 74.105469 170.867188 77.445312 173.5625 C 77.449219 173.5625 77.457031 173.570312 77.457031 173.570312 C 80.617188 176.117188 82.421875 180.066406 82.277344 184.125 L 82.277344 184.148438 C 82.128906 188.441406 83.277344 192.617188 85.601562 196.230469 C 87.921875 199.839844 91.246094 202.617188 95.214844 204.257812 C 98.652344 205.679688 101.320312 208.546875 102.523438 212.035156 L 54.382812 343.640625 C 53.886719 344.996094 54.164062 346.515625 55.101562 347.613281 C 56.039062 348.710938 57.5 349.214844 58.914062 348.929688 L 113.839844 337.945312 L 149.144531 380.53125 C 149.910156 381.453125 151.039062 381.972656 152.214844 381.972656 C 152.441406 381.972656 152.667969 381.953125 152.894531 381.914062 C 154.300781 381.671875 155.472656 380.695312 155.964844 379.351562 L 192.277344 280.074219 L 232.429688 381.476562 C 232.957031 382.8125 234.164062 383.761719 235.589844 383.960938 C 235.773438 383.988281 235.957031 384 236.140625 384 C 237.371094 384 238.546875 383.429688 239.308594 382.433594 L 271.710938 340.0625 L 324.851562 350.003906 C 326.28125 350.273438 327.742188 349.742188 328.667969 348.617188 C 329.59375 347.492188 329.832031 345.957031 329.296875 344.605469 Z M 98.261719 196.871094 C 95.804688 195.855469 93.75 194.136719 92.3125 191.902344 C 90.875 189.667969 90.164062 187.082031 90.253906 184.425781 L 90.253906 184.402344 C 90.367188 181.167969 89.714844 177.902344 88.371094 174.957031 C 87.023438 172.011719 84.984375 169.378906 82.464844 167.351562 C 82.464844 167.347656 82.457031 167.34375 82.457031 167.34375 C 80.386719 165.671875 78.898438 163.441406 78.152344 160.886719 C 77.402344 158.335938 77.453125 155.652344 78.292969 153.125 C 79.316406 150.050781 79.617188 146.730469 79.160156 143.523438 C 78.703125 140.3125 77.484375 137.210938 75.640625 134.542969 L 75.621094 134.519531 C 74.113281 132.335938 73.3125 129.78125 73.3125 127.125 C 73.3125 124.46875 74.113281 121.914062 75.621094 119.734375 L 75.640625 119.707031 C 77.484375 117.042969 78.703125 113.9375 79.160156 110.726562 C 79.617188 107.519531 79.316406 104.199219 78.292969 101.125 C 78.292969 101.121094 78.289062 101.117188 78.289062 101.117188 C 77.449219 98.59375 77.402344 95.914062 78.148438 93.363281 C 78.898438 90.808594 80.386719 88.578125 82.464844 86.902344 C 84.984375 84.871094 87.023438 82.238281 88.371094 79.292969 C 89.714844 76.347656 90.367188 73.082031 90.253906 69.84375 L 90.253906 69.824219 C 90.160156 67.167969 90.871094 64.582031 92.308594 62.34375 C 93.75 60.109375 95.804688 58.390625 98.257812 57.375 C 98.261719 57.375 98.269531 57.371094 98.277344 57.367188 C 101.265625 56.128906 103.96875 54.179688 106.089844 51.734375 C 108.210938 49.28125 109.757812 46.324219 110.5625 43.175781 L 110.5625 43.167969 C 111.222656 40.59375 112.628906 38.3125 114.632812 36.574219 C 116.636719 34.832031 119.09375 33.761719 121.726562 33.476562 L 121.75 33.472656 C 124.972656 33.121094 128.113281 32.011719 130.835938 30.257812 C 133.558594 28.5 135.867188 26.101562 137.515625 23.316406 C 137.515625 23.316406 137.519531 23.308594 137.519531 23.308594 C 138.875 21.019531 140.867188 19.222656 143.285156 18.117188 C 145.703125 17.011719 148.363281 16.675781 150.976562 17.148438 L 150.992188 17.152344 C 154.175781 17.726562 157.5 17.546875 160.601562 16.636719 C 163.707031 15.726562 166.597656 14.078125 168.964844 11.878906 L 168.988281 11.859375 C 170.933594 10.050781 173.351562 8.894531 175.980469 8.519531 C 178.609375 8.144531 181.253906 8.574219 183.628906 9.765625 C 186.527344 11.222656 189.773438 11.992188 193.019531 11.992188 C 196.261719 11.992188 199.507812 11.222656 202.410156 9.765625 C 204.78125 8.574219 207.425781 8.144531 210.054688 8.519531 C 212.683594 8.894531 215.101562 10.050781 217.046875 11.859375 L 217.066406 11.875 C 219.433594 14.078125 222.328125 15.726562 225.429688 16.636719 C 228.535156 17.546875 231.859375 17.726562 235.035156 17.152344 L 235.054688 17.148438 C 237.671875 16.679688 240.332031 17.011719 242.746094 18.121094 C 245.164062 19.226562 247.15625 21.019531 248.511719 23.304688 C 248.511719 23.308594 248.511719 23.308594 248.515625 23.3125 C 250.164062 26.101562 252.476562 28.503906 255.199219 30.257812 C 257.921875 32.011719 261.0625 33.125 264.28125 33.472656 L 264.304688 33.476562 C 266.941406 33.761719 269.394531 34.832031 271.402344 36.574219 C 273.40625 38.3125 274.8125 40.59375 275.472656 43.175781 L 275.476562 43.183594 C 276.277344 46.324219 277.824219 49.28125 279.945312 51.734375 C 282.066406 54.183594 284.773438 56.132812 287.773438 57.378906 C 290.226562 58.394531 292.285156 60.113281 293.722656 62.347656 C 295.160156 64.582031 295.871094 67.167969 295.777344 69.832031 L 295.777344 69.847656 C 295.667969 73.082031 296.316406 76.351562 297.664062 79.292969 C 299.007812 82.238281 301.050781 84.871094 303.578125 86.910156 C 305.644531 88.578125 307.136719 90.808594 307.882812 93.363281 C 308.628906 95.910156 308.582031 98.589844 307.746094 101.109375 C 307.746094 101.113281 307.742188 101.117188 307.742188 101.125 C 306.714844 104.199219 306.417969 107.519531 306.875 110.730469 C 307.332031 113.9375 308.550781 117.042969 310.398438 119.714844 L 310.410156 119.734375 C 311.921875 121.914062 312.71875 124.472656 312.71875 127.125 C 312.71875 129.78125 311.921875 132.339844 310.410156 134.519531 L 310.394531 134.546875 C 308.550781 137.210938 307.332031 140.316406 306.875 143.523438 C 306.417969 146.730469 306.71875 150.054688 307.742188 153.128906 C 307.742188 153.128906 307.742188 153.132812 307.742188 153.132812 C 308.582031 155.65625 308.632812 158.339844 307.882812 160.890625 C 307.136719 163.4375 305.652344 165.667969 303.585938 167.335938 C 303.582031 167.339844 303.574219 167.34375 303.570312 167.351562 C 301.050781 169.382812 299.007812 172.011719 297.664062 174.957031 C 296.320312 177.902344 295.667969 181.167969 295.78125 184.398438 L 295.78125 184.425781 C 295.875 187.085938 295.160156 189.671875 293.722656 191.90625 C 292.285156 194.140625 290.230469 195.859375 287.785156 196.871094 C 287.78125 196.871094 287.769531 196.875 287.769531 196.878906 C 284.773438 198.117188 282.070312 200.066406 279.945312 202.519531 C 277.824219 204.96875 276.277344 207.925781 275.476562 211.0625 L 275.472656 211.082031 C 274.941406 213.15625 273.921875 215.042969 272.496094 216.609375 C 272.476562 216.628906 272.457031 216.648438 272.4375 216.671875 C 272.113281 217.023438 271.769531 217.359375 271.402344 217.675781 C 269.398438 219.417969 266.941406 220.488281 264.308594 220.773438 L 264.285156 220.777344 C 261.0625 221.125 257.921875 222.238281 255.199219 223.992188 C 252.476562 225.746094 250.167969 228.148438 248.515625 230.9375 C 248.511719 230.941406 248.511719 230.949219 248.503906 230.957031 C 247.152344 233.238281 245.160156 235.027344 242.75 236.128906 C 240.335938 237.234375 237.675781 237.570312 235.0625 237.101562 L 235.054688 237.101562 C 235.050781 237.097656 235.046875 237.097656 235.042969 237.097656 C 231.859375 236.523438 228.535156 236.703125 225.433594 237.613281 C 222.328125 238.523438 219.4375 240.171875 217.0625 242.378906 L 217.050781 242.390625 C 215.105469 244.199219 212.6875 245.355469 210.058594 245.730469 C 207.429688 246.105469 204.785156 245.675781 202.410156 244.484375 C 202.152344 244.355469 201.890625 244.234375 201.625 244.117188 C 201.550781 244.078125 201.472656 244.042969 201.394531 244.011719 C 198.761719 242.863281 195.886719 242.261719 193.019531 242.261719 C 189.773438 242.261719 186.527344 243.027344 183.628906 244.484375 C 181.253906 245.675781 178.609375 246.105469 175.980469 245.730469 C 173.351562 245.355469 170.933594 244.199219 168.984375 242.386719 L 168.96875 242.375 C 166.601562 240.171875 163.707031 238.523438 160.605469 237.613281 C 157.507812 236.707031 154.1875 236.527344 151.011719 237.097656 L 150.996094 237.097656 C 150.992188 237.101562 150.988281 237.101562 150.980469 237.101562 C 148.367188 237.574219 145.707031 237.238281 143.289062 236.132812 C 140.875 235.027344 138.878906 233.230469 137.523438 230.941406 C 135.871094 228.152344 133.558594 225.75 130.835938 223.996094 C 128.117188 222.242188 124.972656 221.128906 121.746094 220.777344 L 121.734375 220.777344 C 119.097656 220.492188 116.640625 219.417969 114.636719 217.679688 C 112.632812 215.9375 111.222656 213.65625 110.570312 211.089844 L 110.5625 211.066406 C 109.761719 207.925781 108.214844 204.96875 106.09375 202.519531 C 103.964844 200.066406 101.261719 198.113281 98.261719 196.871094 Z M 188.382812 267.480469 L 150.851562 370.078125 L 118.460938 331.011719 C 117.527344 329.882812 116.046875 329.355469 114.609375 329.644531 L 64.328125 339.699219 L 107.457031 221.789062 C 108.058594 222.464844 108.710938 223.109375 109.402344 223.710938 C 112.644531 226.523438 116.609375 228.257812 120.878906 228.71875 L 120.890625 228.71875 C 124.933594 229.15625 128.582031 231.507812 130.65625 235.011719 C 132.84375 238.710938 136.0625 241.609375 139.96875 243.394531 C 143.867188 245.179688 148.160156 245.722656 152.382812 244.964844 L 152.394531 244.960938 C 152.398438 244.960938 152.40625 244.960938 152.410156 244.960938 C 156.402344 244.238281 160.5625 245.460938 163.539062 248.226562 L 163.554688 248.242188 C 166.695312 251.164062 170.601562 253.03125 174.851562 253.636719 C 179.097656 254.246094 183.367188 253.546875 187.203125 251.625 C 189.519531 250.460938 192.121094 250.039062 194.644531 250.359375 Z M 270.761719 331.757812 C 269.285156 331.480469 267.773438 332.058594 266.859375 333.253906 L 237.253906 371.972656 L 196.398438 268.800781 L 202.191406 252.964844 C 204.140625 253.554688 206.160156 253.851562 208.195312 253.851562 C 209.191406 253.851562 210.1875 253.78125 211.183594 253.640625 C 215.429688 253.03125 219.335938 251.164062 222.484375 248.238281 L 222.496094 248.226562 C 225.46875 245.460938 229.628906 244.242188 233.617188 244.960938 L 233.625 244.960938 C 233.628906 244.960938 233.632812 244.960938 233.636719 244.960938 C 237.863281 245.722656 242.160156 245.183594 246.066406 243.394531 C 249.96875 241.609375 253.191406 238.710938 255.378906 235.011719 C 255.382812 235.007812 255.382812 235.003906 255.386719 234.996094 C 257.460938 231.503906 261.105469 229.15625 265.132812 228.71875 L 265.160156 228.714844 C 268.207031 228.386719 271.101562 227.40625 273.6875 225.851562 L 319.207031 340.820312 Z M 270.761719 331.757812 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tQualit\u00e4tsgarantie bei jeder W\u00e4sche\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWir bei TexClean in kiel und Umgebung setzen auf h\u00f6chste Qualit\u00e4tsstandards. Unsere erfahrenen Partner sorgen daf\u00fcr, dass deine W\u00e4sche immer makellos gereinigt und geb\u00fcgelt zu dir zur\u00fcckkehrt.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-361bf07 elementor-widget elementor-widget-spacer\" data-id=\"361bf07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b8cb2e1\" data-eae-slider=\"62663\" data-id=\"b8cb2e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18c3f2d elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"18c3f2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"512\" viewbox=\"0 0 384 383.999986\" height=\"512\" preserveaspectratio=\"xMidYMid meet\"><defs><clippath id=\"6c6eb8874c\"><path d=\"M 7.199219 203 L 375 203 L 375 384 L 7.199219 384 Z M 7.199219 203 \" clip-rule=\"nonzero\"><\/path><\/clippath><\/defs><g clip-path=\"url(#6c6eb8874c)\"><path fill=\"#000000\" d=\"M 347.238281 204 C 340.035156 203.699219 333.433594 206.398438 328.332031 211.5 L 262.304688 264.597656 C 262.605469 266.097656 262.902344 267.898438 263.203125 269.398438 C 263.503906 272.699219 263.503906 276 262.902344 279.300781 L 336.132812 220.5 C 336.433594 220.199219 336.433594 220.199219 336.734375 219.898438 C 339.433594 217.199219 343.035156 215.699219 346.636719 215.699219 C 350.839844 215.699219 355.042969 218.101562 358.042969 221.699219 C 364.042969 228.898438 363.746094 240.300781 357.742188 247.199219 L 246.695312 346.199219 C 246.695312 346.199219 246.398438 346.5 246.398438 346.5 C 240.394531 352.5 234.390625 355.800781 226.890625 356.699219 C 221.1875 357.300781 214.882812 356.699219 208.582031 354.300781 L 111.640625 319.199219 C 111.640625 319.199219 111.34375 319.199219 111.34375 319.199219 L 109.839844 318.898438 C 104.441406 317.398438 98.136719 315.300781 92.132812 316.800781 L 66.324219 246 L 101.136719 219.601562 C 105.339844 217.199219 107.441406 217.199219 109.542969 217.5 L 216.683594 250.5 C 216.984375 250.5 216.984375 250.5 217.285156 250.800781 C 226.890625 252.597656 237.992188 261.300781 238.894531 271.800781 C 239.496094 278.097656 237.394531 284.097656 233.492188 288.300781 C 230.191406 291.597656 225.988281 293.097656 221.785156 292.800781 L 155.761719 274.5 C 152.457031 273.597656 149.15625 275.398438 148.257812 278.699219 C 147.355469 282 149.15625 285.300781 152.457031 286.199219 L 219.085938 304.800781 C 219.386719 304.800781 219.6875 305.097656 219.984375 305.097656 C 220.886719 305.097656 221.785156 305.097656 222.6875 305.097656 C 229.890625 305.097656 236.492188 302.398438 241.894531 297 C 248.496094 290.398438 251.800781 281.097656 250.898438 271.199219 C 249.398438 255 234.09375 242.398438 219.6875 239.699219 L 112.242188 206.699219 C 111.941406 206.699219 111.640625 206.398438 111.34375 206.398438 C 107.140625 205.800781 102.039062 205.5 94.535156 210 C 94.234375 210 94.234375 210.300781 93.933594 210.300781 L 61.820312 234.601562 L 57.019531 222 C 55.519531 218.398438 52.820312 215.398438 49.21875 213.898438 C 45.316406 212.398438 41.113281 212.398438 37.210938 213.898438 L 11.703125 224.101562 C 8.699219 225.300781 7.199219 228.898438 8.402344 231.898438 C 9.601562 234.898438 13.203125 236.398438 16.203125 235.199219 L 42.015625 225 C 42.914062 224.699219 43.816406 224.699219 44.714844 225 C 45.015625 225.300781 45.617188 225.601562 45.914062 226.199219 L 92.132812 351.597656 C 92.734375 353.097656 91.835938 354.898438 90.332031 355.5 L 48.917969 372.597656 C 45.914062 373.796875 44.414062 377.398438 45.617188 380.398438 C 46.515625 382.796875 48.917969 384 51.019531 384 C 51.917969 384 52.519531 384 53.417969 383.398438 L 94.835938 366.300781 C 102.339844 363 106.238281 354.597656 103.238281 347.097656 L 96.335938 328.199219 C 98.738281 327.898438 102.039062 328.800781 106.539062 330.300781 L 204.679688 365.699219 C 210.683594 367.796875 216.984375 369 222.6875 369 C 224.488281 369 226.589844 369 228.390625 368.699219 C 238.292969 367.5 246.695312 363 254.800781 355.199219 L 365.84375 256.199219 C 365.84375 256.199219 366.144531 255.898438 366.144531 255.898438 C 376.648438 244.800781 376.949219 226.199219 367.347656 214.5 C 362.242188 207.898438 354.742188 204.300781 347.238281 204 Z M 347.238281 204 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#000000\" d=\"M 149.757812 143.398438 C 149.757812 146.699219 150.957031 149.699219 153.359375 151.800781 L 197.175781 195.601562 C 200.777344 199.199219 205.28125 201 210.082031 201 C 214.585938 201 219.085938 199.199219 222.6875 195.898438 L 314.222656 108 C 316.625 105.601562 317.824219 102.601562 317.824219 99.601562 C 317.824219 96.300781 316.625 93.300781 314.222656 91.199219 L 301.320312 78.601562 C 296.515625 74.101562 289.3125 74.101562 284.511719 78.601562 L 210.082031 148.800781 L 183.070312 122.402344 C 178.269531 117.902344 170.765625 117.902344 165.964844 122.402344 L 153.359375 135 C 150.957031 137.101562 149.757812 140.101562 149.757812 143.398438 Z M 174.667969 131.101562 L 201.679688 157.5 C 206.480469 162 213.683594 162 218.484375 157.5 L 292.914062 87 L 305.820312 99.300781 L 214.285156 187.199219 C 211.882812 189.601562 207.980469 189.601562 205.582031 187.199219 L 161.761719 143.699219 Z M 174.667969 131.101562 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 199.277344 5.101562 C 195.976562 6 194.175781 9.300781 195.078125 12.601562 C 195.976562 15.300781 198.078125 16.800781 200.777344 16.800781 C 201.378906 16.800781 201.980469 16.800781 202.277344 16.5 C 205.582031 15.601562 207.382812 12.300781 206.480469 9 C 205.878906 6 202.578125 4.203125 199.277344 5.101562 Z M 199.277344 5.101562 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 220.585938 0.902344 C 217.285156 1.203125 214.882812 4.203125 215.183594 7.5 C 215.484375 10.5 218.1875 12.902344 221.1875 12.902344 C 221.488281 12.902344 221.488281 12.902344 221.785156 12.902344 C 225.089844 12.601562 227.488281 9.601562 227.1875 6.300781 C 226.890625 3 223.886719 0.601562 220.585938 0.902344 Z M 220.585938 0.902344 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 178.871094 12.902344 C 175.867188 14.402344 174.667969 18 175.867188 21 C 176.769531 23.101562 179.167969 24.601562 181.269531 24.601562 C 182.171875 24.601562 183.070312 24.300781 183.972656 24 C 186.972656 22.5 188.171875 18.902344 186.972656 15.902344 C 185.773438 12.902344 181.871094 11.402344 178.871094 12.902344 Z M 178.871094 12.902344 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 236.191406 6 C 236.191406 9.300781 238.59375 12 241.894531 12.300781 C 241.894531 12.300781 241.894531 12.300781 242.195312 12.300781 C 245.496094 12.300781 248.199219 9.902344 248.199219 6.601562 C 248.199219 3 245.496094 0.300781 242.496094 0 C 238.894531 0 236.191406 2.402344 236.191406 6 Z M 236.191406 6 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 129.949219 61.800781 C 131.148438 62.699219 132.351562 63 133.550781 63 C 135.351562 63 137.152344 62.101562 138.351562 60.601562 C 140.453125 57.902344 139.855469 54.300781 137.152344 52.199219 C 134.453125 50.101562 130.851562 50.699219 128.75 53.402344 C 126.648438 56.101562 127.25 60 129.949219 61.800781 Z M 129.949219 61.800781 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 160.261719 23.699219 C 157.5625 25.5 156.960938 29.402344 158.761719 32.101562 C 159.960938 33.902344 161.761719 34.800781 163.5625 34.800781 C 164.765625 34.800781 165.964844 34.5 166.863281 33.601562 C 169.566406 31.800781 170.167969 27.902344 168.367188 25.199219 C 166.566406 22.5 162.964844 21.902344 160.261719 23.699219 Z M 160.261719 23.699219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 143.15625 37.199219 C 140.753906 39.601562 140.753906 43.199219 142.855469 45.601562 C 144.054688 46.800781 145.554688 47.402344 147.058594 47.402344 C 148.558594 47.402344 150.058594 46.800781 151.257812 45.601562 C 153.660156 43.199219 153.660156 39.601562 151.558594 37.199219 C 149.457031 35.101562 145.554688 35.101562 143.15625 37.199219 Z M 143.15625 37.199219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 350.839844 63 C 349.039062 60.300781 345.4375 59.402344 342.4375 61.199219 C 339.734375 63 338.835938 66.601562 340.636719 69.601562 C 341.835938 71.402344 343.636719 72.300781 345.738281 72.300781 C 346.9375 72.300781 347.839844 72 349.039062 71.402344 C 351.738281 69.601562 352.640625 66 350.839844 63 Z M 350.839844 63 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 108.039062 149.699219 C 104.738281 150.300781 102.640625 153.300781 102.9375 156.601562 C 103.539062 159.601562 105.941406 161.699219 108.941406 161.699219 C 109.242188 161.699219 109.542969 161.699219 109.839844 161.699219 C 113.144531 161.101562 115.242188 158.101562 114.644531 154.800781 C 114.34375 151.5 111.34375 149.101562 108.039062 149.699219 Z M 108.039062 149.699219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 125.148438 69.300781 C 122.148438 67.800781 118.546875 69 117.042969 71.699219 C 115.542969 74.699219 116.746094 78.300781 119.445312 79.800781 C 120.347656 80.402344 121.246094 80.402344 122.148438 80.402344 C 124.246094 80.402344 126.347656 79.199219 127.546875 77.101562 C 129.347656 74.402344 128.148438 70.800781 125.148438 69.300781 Z M 125.148438 69.300781 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 360.441406 98.699219 C 357.140625 99.601562 355.339844 102.601562 355.941406 105.902344 C 356.542969 108.601562 358.941406 110.402344 361.644531 110.402344 C 362.242188 110.402344 362.542969 110.402344 363.144531 110.101562 C 366.445312 109.199219 368.246094 106.199219 367.644531 102.902344 C 367.046875 99.902344 363.746094 97.800781 360.441406 98.699219 Z M 360.441406 98.699219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 127.25 198 C 128.449219 196.199219 128.449219 194.101562 127.546875 192 C 126.046875 189 122.445312 187.800781 119.445312 189.601562 C 117.34375 190.5 116.445312 192.601562 116.144531 194.699219 Z M 127.25 198 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 114.042969 181.800781 C 114.644531 181.800781 115.242188 181.800781 115.84375 181.5 C 118.84375 180.601562 120.644531 177 119.746094 174 C 118.84375 171 115.242188 169.199219 112.242188 170.101562 C 109.242188 171 107.441406 174.601562 108.339844 177.601562 C 109.242188 180.300781 111.640625 181.800781 114.042969 181.800781 Z M 114.042969 181.800781 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 352.941406 79.199219 C 349.9375 80.402344 348.4375 84 349.640625 87 C 350.539062 89.402344 352.941406 90.601562 355.042969 90.601562 C 355.941406 90.601562 356.542969 90.601562 357.441406 90 C 360.441406 88.800781 361.945312 85.199219 360.742188 82.199219 C 359.542969 79.199219 355.941406 78 352.941406 79.199219 Z M 352.941406 79.199219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 329.230469 45.300781 C 326.828125 47.402344 326.53125 51.300781 328.628906 53.699219 C 329.832031 55.199219 331.632812 55.800781 333.132812 55.800781 C 334.632812 55.800781 336.132812 55.199219 337.035156 54.300781 C 339.433594 52.199219 339.734375 48.300781 337.632812 45.902344 C 335.53125 43.199219 331.933594 42.902344 329.230469 45.300781 Z M 329.230469 45.300781 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 313.625 31.5 C 311.523438 33.902344 311.824219 37.800781 314.523438 39.902344 C 315.726562 40.800781 316.925781 41.402344 318.425781 41.402344 C 320.226562 41.402344 321.726562 40.5 322.929688 39.300781 C 325.027344 36.601562 324.730469 33 322.027344 30.902344 C 319.625 28.5 315.726562 28.800781 313.625 31.5 Z M 313.625 31.5 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 108.640625 91.800781 C 107.742188 94.800781 109.242188 98.402344 112.542969 99.300781 C 113.144531 99.601562 113.742188 99.601562 114.34375 99.601562 C 116.746094 99.601562 119.144531 98.101562 120.046875 95.402344 C 121.246094 92.402344 119.445312 88.800781 116.144531 87.902344 C 112.84375 87 109.542969 88.5 108.640625 91.800781 Z M 108.640625 91.800781 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 371.246094 124.5 C 370.949219 121.199219 368.246094 118.800781 364.945312 119.101562 C 361.644531 119.402344 359.242188 122.101562 359.542969 125.402344 C 359.84375 128.398438 362.542969 130.800781 365.546875 130.800781 C 365.546875 130.800781 365.84375 130.800781 365.84375 130.800781 C 368.847656 130.5 371.546875 127.800781 371.246094 124.5 Z M 371.246094 124.5 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 367.644531 167.398438 C 368.546875 164.101562 366.445312 160.800781 363.144531 160.199219 C 359.84375 159.300781 356.542969 161.398438 355.941406 164.699219 C 355.042969 168 357.140625 171.300781 360.441406 171.898438 C 361.042969 171.898438 361.34375 172.199219 361.945312 172.199219 C 364.34375 172.199219 367.046875 170.398438 367.644531 167.398438 Z M 367.644531 167.398438 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 370.949219 146.101562 C 371.246094 142.800781 368.847656 139.800781 365.546875 139.5 C 362.242188 139.199219 359.242188 141.601562 358.941406 144.898438 C 358.640625 148.199219 361.042969 151.199219 364.34375 151.5 C 364.644531 151.5 364.644531 151.5 364.945312 151.5 C 368.246094 151.5 370.949219 149.398438 370.949219 146.101562 Z M 370.949219 146.101562 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 256.902344 7.5 C 256.300781 10.800781 258.402344 13.800781 261.402344 14.699219 C 261.703125 14.699219 262.304688 14.699219 262.605469 14.699219 C 265.304688 14.699219 268.003906 12.601562 268.605469 9.902344 C 269.207031 6.601562 267.105469 3.601562 263.804688 2.703125 C 260.503906 2.101562 257.5 4.203125 256.902344 7.5 Z M 256.902344 7.5 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 101.4375 134.699219 C 101.4375 135 101.4375 135 101.4375 134.699219 C 101.4375 138.300781 104.140625 141 107.441406 141 C 110.742188 141 113.441406 138.300781 113.441406 135 C 113.441406 135 113.441406 135 113.441406 134.699219 C 113.441406 134.699219 113.441406 134.398438 113.441406 134.398438 C 113.441406 131.101562 110.742188 128.402344 107.441406 128.402344 C 104.140625 128.402344 101.4375 131.101562 101.4375 134.398438 C 101.4375 134.699219 101.4375 134.699219 101.4375 134.699219 Z M 101.4375 134.699219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 103.238281 112.800781 C 102.640625 116.101562 105.039062 119.101562 108.339844 119.699219 C 108.640625 119.699219 108.941406 119.699219 109.242188 119.699219 C 112.242188 119.699219 114.644531 117.601562 115.242188 114.601562 C 115.84375 111.300781 113.441406 108.300781 110.140625 107.699219 C 106.839844 107.402344 103.839844 109.5 103.238281 112.800781 Z M 103.238281 112.800781 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 296.21875 20.402344 C 294.417969 23.402344 295.617188 27 298.316406 28.5 C 299.21875 29.101562 300.417969 29.402344 301.320312 29.402344 C 303.421875 29.402344 305.519531 28.199219 306.421875 26.402344 C 307.921875 23.402344 307.023438 19.800781 304.320312 18.300781 C 301.320312 16.5 297.71875 17.402344 296.21875 20.402344 Z M 296.21875 20.402344 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 280.3125 20.101562 C 280.910156 20.402344 281.8125 20.402344 282.410156 20.402344 C 284.8125 20.402344 287.214844 18.902344 288.113281 16.5 C 289.3125 13.5 287.8125 9.902344 284.8125 8.699219 C 281.8125 7.5 278.210938 9 277.007812 12 C 275.808594 15.300781 277.308594 18.902344 280.3125 20.101562 Z M 280.3125 20.101562 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#000000\" d=\"M 357.441406 180.300781 C 354.441406 179.101562 350.839844 180.300781 349.640625 183.300781 C 348.4375 186.300781 349.640625 189.898438 352.640625 191.101562 C 353.539062 191.398438 354.140625 191.699219 355.042969 191.699219 C 357.441406 191.699219 359.542969 190.199219 360.441406 188.101562 C 361.945312 185.101562 360.441406 181.5 357.441406 180.300781 Z M 357.441406 180.300781 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMobile Textilreinigung &amp; W\u00e4scherei in Kiel &amp; Umgebung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUnser W\u00e4sche- und B\u00fcgelservice ist deiner Umgebung verf\u00fcgbar. Egal, wo du bist, TexClean ist stets in deiner N\u00e4he, bereit, dir zu dienen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d4fa9b elementor-widget elementor-widget-spacer\" data-id=\"7d4fa9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c1e3014\" data-eae-slider=\"38599\" data-id=\"c1e3014\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8fa0c7 elementor-widget elementor-widget-spacer\" data-id=\"d8fa0c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-bfd0e90 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"33075\" data-id=\"bfd0e90\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-82fac0e\" data-eae-slider=\"12584\" data-id=\"82fac0e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-inner-section elementor-element elementor-element-53c83d5 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"49711\" data-id=\"53c83d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-96ee62a\" data-eae-slider=\"21443\" data-id=\"96ee62a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fad4851 elementor-widget elementor-widget-image\" data-id=\"fad4851\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"582\" src=\"https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Design-ohne-Titel-2023-12-19T011127.914-1024x582.png\" class=\"attachment-large size-large wp-image-733\" alt=\"\" srcset=\"https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Design-ohne-Titel-2023-12-19T011127.914-1024x582.png 1024w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Design-ohne-Titel-2023-12-19T011127.914-300x171.png 300w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Design-ohne-Titel-2023-12-19T011127.914-768x437.png 768w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Design-ohne-Titel-2023-12-19T011127.914-1536x873.png 1536w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Design-ohne-Titel-2023-12-19T011127.914-600x341.png 600w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Design-ohne-Titel-2023-12-19T011127.914.png 1900w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-914a5d7\" data-eae-slider=\"5594\" data-id=\"914a5d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1b28e0 elementor-widget elementor-widget-heading\" data-id=\"f1b28e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Liefer- und Abholservice: \u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae0c8d8 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ae0c8d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mit unserem exklusiven Abhol- und Lieferservice TexClean Textilreinigung in kiel und Umgebung , m\u00fcssen Sie sich keine Sorgen um schmutzige Kleidung machen egal ob Sie Anzug haben , Kleid , Oder Hemd. Bestellen Sie bequem online, und wir bringen sie, bearbeitet mit den neuesten Reinigungs- und B\u00fcgeltechniken, in 48 Stunden zu Ihnen nach Hause.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-7786f89 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"25344\" data-id=\"7786f89\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ded2a63\" data-eae-slider=\"14038\" data-id=\"ded2a63\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-inner-section elementor-element elementor-element-dbab3c1 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"66683\" data-id=\"dbab3c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7d4d8af\" data-eae-slider=\"80519\" data-id=\"7d4d8af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-791023b elementor-widget elementor-widget-image\" data-id=\"791023b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-1-1024x1024.png\" class=\"attachment-large size-large wp-image-736\" alt=\"\" srcset=\"https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-1-1024x1024.png 1024w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-1-300x300.png 300w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-1-150x150.png 150w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-1-768x768.png 768w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-1-600x600.png 600w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-1-100x100.png 100w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-1.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-522164a\" data-eae-slider=\"33874\" data-id=\"522164a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3daf102 elementor-widget elementor-widget-heading\" data-id=\"3daf102\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Luxusdienstleistungen: <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48877e4 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"48877e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>in TexClean Textilreinigung in kiel und Umgebung .Wir betrachten Reinigung als Kunst, und jedes Kleidungsst\u00fcck , Anzug , Abendkleid , oder Daunen Jacke \u00a0wird mit k\u00fcnstlerischer Sorgfalt und Pr\u00e4zision behandelt. Mit den neuesten Technologien und den besten Materialien sind wir hier, um Ihnen Momente der Entspannung und Eleganz zu bieten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-51ad739 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"8920\" data-id=\"51ad739\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8bbce0c\" data-eae-slider=\"44062\" data-id=\"8bbce0c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52739ff elementor-widget elementor-widget-image\" data-id=\"52739ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/texclean-sh.de\/wp-content\/uploads\/2024\/01\/Design-ohne-Titel-2024-01-01T195703.236-1024x1024.png\" class=\"attachment-large size-large wp-image-1269\" alt=\"\" srcset=\"https:\/\/texclean-sh.de\/wp-content\/uploads\/2024\/01\/Design-ohne-Titel-2024-01-01T195703.236-1024x1024.png 1024w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2024\/01\/Design-ohne-Titel-2024-01-01T195703.236-300x300.png 300w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2024\/01\/Design-ohne-Titel-2024-01-01T195703.236-150x150.png 150w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2024\/01\/Design-ohne-Titel-2024-01-01T195703.236-768x768.png 768w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2024\/01\/Design-ohne-Titel-2024-01-01T195703.236-600x600.png 600w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2024\/01\/Design-ohne-Titel-2024-01-01T195703.236-100x100.png 100w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2024\/01\/Design-ohne-Titel-2024-01-01T195703.236.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7fb001 elementor-widget elementor-widget-heading\" data-id=\"a7fb001\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Au\u00dfergew\u00f6hnliche Kundenerfahrung: <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11b1a9c elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"11b1a9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00dcberschreiten Sie die Grenzen herk\u00f6mmlicher Dienstleistungen und nehmen Sie sich Zeit, Ihr Leben zu genie\u00dfen. W\u00e4hlen Sie TexClean Textilreinigung in kiel und Umgebung f\u00fcr eine unvergessliche Erfahrung, in der Luxus und Eleganz zu einem unverzichtbaren Teil Ihrer t\u00e4glichen Routine werden.<\/p><p>Willkommen in der Welt des Luxus und der Professionalit\u00e4t mit TexClean Lassen Sie uns die Details Ihres Lebens k\u00fcmmern, und genie\u00dfen Sie die Momente des Glanzes und der Entspannung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-inner-section elementor-element elementor-element-719df8e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"66570\" data-id=\"719df8e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;curve&quot;,&quot;shape_divider_top_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,97C126.7,96.3,0.8,19.8,0,0v100l1000,0V1C1000,19.4,873.3,97.8,500,97z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b626366\" data-eae-slider=\"57098\" data-id=\"b626366\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea09405 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ea09405\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#link\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt mehr erfahren <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-45f2644\" data-eae-slider=\"39658\" data-id=\"45f2644\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8ba5d1e\" data-eae-slider=\"63735\" data-id=\"8ba5d1e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2c4056 elementor-widget elementor-widget-image\" data-id=\"e2c4056\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-4-1024x1024.png\" class=\"attachment-large size-large wp-image-745\" alt=\"\" srcset=\"https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-4-1024x1024.png 1024w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-4-300x300.png 300w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-4-150x150.png 150w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-4-768x768.png 768w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-4-600x600.png 600w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-4-100x100.png 100w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-4.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94446e4 elementor-widget elementor-widget-heading\" data-id=\"94446e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ihre Zeit ist uns wichtig und geh\u00f6rt Ihnen: <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7573019 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7573019\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In unserem Unternehmen glauben wir, dass Ihre Zeit von h\u00f6chster Bedeutung ist. k\u00f6nnen Sie die Abhol- und Lieferzeit w\u00e4hlen, die Ihnen am besten passt, egal ob Sie bei der Arbeit, zu Hause, im Hotel oder im Urlaub sind. Wir sind hier, um Ihnen einen flexiblen Service zu bieten, der Ihre Bed\u00fcrfnisse erf\u00fcllt und Reinigung und B\u00fcgeln zu einer einfachen und bequemen Erfahrung macht. Ohne unseren Service k\u00f6nnte der Kunde viel Zeit mit der Suche nach herk\u00f6mmlichen Reinigungsdiensten und dem pers\u00f6nlichen Besuch von Reinigungsgesch\u00e4ften verlieren.<\/p><p>Traditionelle Reinigung erfordert zus\u00e4tzlichen Aufwand wie das Tragen von Kleidung und das pers\u00f6nliche Abholen, w\u00e4hrend unser Service Bequemlichkeit bietet.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-daca7e9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"daca7e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Keine l\u00e4stigen Fahrten zu Textilreinigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wunschtermin und Wunschort<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pers\u00f6nliche Kundenbetreuung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Einfaches Bestellen online via Web und App<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-inner-section elementor-element elementor-element-eb92429 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"83974\" data-id=\"eb92429\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;curve&quot;,&quot;shape_divider_top_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,97C126.7,96.3,0.8,19.8,0,0v100l1000,0V1C1000,19.4,873.3,97.8,500,97z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-87db660\" data-eae-slider=\"99873\" data-id=\"87db660\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a8f087 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0a8f087\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#link\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt mehr erfahren <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8a5d4ac\" data-eae-slider=\"14262\" data-id=\"8a5d4ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-43551a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"69996\" data-id=\"43551a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa5959a\" data-eae-slider=\"13454\" data-id=\"fa5959a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-inner-section elementor-element elementor-element-b21aaa7 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"58099\" data-id=\"b21aaa7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9bccbda\" data-eae-slider=\"92954\" data-id=\"9bccbda\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8eb17e elementor-widget elementor-widget-image\" data-id=\"d8eb17e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-1024x1024.png\" class=\"attachment-large size-large wp-image-735\" alt=\"\" srcset=\"https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-1024x1024.png 1024w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-300x300.png 300w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-150x150.png 150w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-768x768.png 768w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-600x600.png 600w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px-100x100.png 100w, https:\/\/texclean-sh.de\/wp-content\/uploads\/2023\/12\/Kein-Titel-1080-x-1080-px.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9a342fb\" data-eae-slider=\"54216\" data-id=\"9a342fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cb7ea1 elementor-widget elementor-widget-heading\" data-id=\"4cb7ea1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Engagement f\u00fcr die Umwelt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23553be elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"23553be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir bieten nicht nur Reinigungs- und B\u00fcgeldienstleistungen an, sondern setzen auch auf Nachhaltigkeit. Durch die Verwendung umweltfreundlicher Materialien streben wir \u00fcberlegene Sauberkeit bei umweltbewusster Verantwortung an.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-a895924 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"61648\" data-id=\"a895924\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d563d0\" data-eae-slider=\"45258\" data-id=\"3d563d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6086b0 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f6086b0\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"arrow-heading\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Individuelle L\u00f6sungen <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-d42ab51 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"45270\" data-id=\"d42ab51\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db0f36b\" data-eae-slider=\"23308\" data-id=\"db0f36b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b07ca99 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b07ca99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d562d93 elementor-widget elementor-widget-heading\" data-id=\"d562d93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">F\u00fcr jeden der richtige Service\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-8e69db2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"56174\" data-id=\"8e69db2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac33269\" data-eae-slider=\"40747\" data-id=\"ac33269\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-c61bba4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"4160\" data-id=\"c61bba4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd6ce52\" data-eae-slider=\"9126\" data-id=\"bd6ce52\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5410a7e elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"5410a7e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"arrow-heading\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"#link\">Jetzt Verf\u00fcgbarkeit pr\u00fcfen<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-a0c67cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"32283\" data-id=\"a0c67cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-21cbe51\" data-eae-slider=\"72348\" data-id=\"21cbe51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-786e5f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"64440\" data-id=\"786e5f4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f9e8c1d\" data-eae-slider=\"42088\" data-id=\"f9e8c1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fefbd3c elementor-widget elementor-widget-heading\" data-id=\"fefbd3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Partnerfilialen in Kiel und Umgebung:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-39025b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"28563\" data-id=\"39025b2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b90c9d\" data-eae-slider=\"59387\" data-id=\"6b90c9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4b7b7b elementor-widget elementor-widget-text-editor\" data-id=\"d4b7b7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"margin: 0cm; margin-bottom: .0001pt;\"><strong>Tex Clean Reinigung<\/strong><\/p><p style=\"margin: 0cm; margin-bottom: .0001pt;\"><strong><span style=\"vertical-align: inherit;\">winterbeker weg 44<\/span><\/strong><\/p><p style=\"margin: 0cm; margin-bottom: .0001pt;\"><strong><span style=\"vertical-align: inherit;\">24114 Kiel<\/span><\/strong><\/p><p style=\"margin: 0cm; margin-bottom: .0001pt;\"><strong>0431687834<\/strong><\/p><p>\u00a0<\/p><p style=\"margin: 0cm; margin-bottom: .0001pt;\"><strong>TexFit<\/strong><\/p><p style=\"margin: 0cm; margin-bottom: .0001pt;\"><strong>Mergenthalerstra\u00dfe 13-21<\/strong><\/p><p style=\"margin: 0cm; margin-bottom: .0001pt;\"><strong>24223 Schwentinetal<\/strong><\/p><p style=\"margin: 0cm; margin-bottom: .0001pt;\"><strong>043071607<\/strong><\/p><p>\u00a0<\/p><p style=\"margin-bottom: .0001pt;\"><strong>Tex Clean Reinigung<\/strong><\/p><p style=\"margin: 0cm; margin-bottom: .0001pt;\"><strong>Altenholzer Str 5-7<\/strong><\/p><p style=\"margin: 0cm; margin-bottom: .0001pt;\"><strong>24161 Altenholz<\/strong><\/p><p style=\"margin: 0cm; margin-bottom: .0001pt;\"><strong>043132716<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-f6b4a6f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"31771\" data-id=\"f6b4a6f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0e07d11\" data-eae-slider=\"63113\" data-id=\"0e07d11\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Dein mobiler W\u00e4scheservice in Kiel &#038; Umgebung abholen &#8211; reinigen &amp; b\u00fcgeln &#8211; liefern Mehr Infos Wir reinigen Smart Mobile Textilreinigung &#038; W\u00e4scherei in Kiel &#038; Umgebung Textilpflege in nur 48h Bei TexClean Textilreinigung in kiel und Umgebung garantieren wir eine schnelle Reinigung \u2013 im Durchschnitt dauert es nur 48 Stunden, bis wir deine Kleidung [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mobile Textilreinigung &amp; W\u00e4scherei in Kiel &amp; Umgebung<\/title>\n<meta name=\"description\" content=\"Mobile Textilreinigung &amp; W\u00e4scherei in Kiel &amp; Umgebung -Xpress Reinigung in 48 Stunden - Anzug Reinigung Kiel -Chemische Reinigung Abholservice\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/texclean-sh.de\/en\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home\" \/>\n<meta property=\"og:description\" content=\"Mobile Textilreinigung &amp; W\u00e4scherei in Kiel &amp; Umgebung -Xpress Reinigung in 48 Stunden - Anzug Reinigung Kiel -Chemische Reinigung Abholservice\" \/>\n<meta property=\"og:url\" content=\"https:\/\/texclean-sh.de\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Tex Clean\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tex.Clean.Reinigung\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-13T09:43:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/texclean-sh.de\/wp-content\/uploads\/2025\/05\/Untitled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/texclean-sh.de\\\/\",\"url\":\"https:\\\/\\\/texclean-sh.de\\\/\",\"name\":\"Mobile Textilreinigung & W\u00e4scherei in Kiel & Umgebung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/texclean-sh.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/texclean-sh.de\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/texclean-sh.de\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/texclean-sh.de\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Untitled-1.jpg\",\"datePublished\":\"2023-12-02T06:55:45+00:00\",\"dateModified\":\"2025-05-13T09:43:50+00:00\",\"description\":\"Mobile Textilreinigung & W\u00e4scherei in Kiel & Umgebung -Xpress Reinigung in 48 Stunden - Anzug Reinigung Kiel -Chemische Reinigung Abholservice\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/texclean-sh.de\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/texclean-sh.de\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/texclean-sh.de\\\/#primaryimage\",\"url\":\"https:\\\/\\\/texclean-sh.de\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Untitled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/texclean-sh.de\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Untitled-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/texclean-sh.de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/texclean-sh.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/texclean-sh.de\\\/#website\",\"url\":\"https:\\\/\\\/texclean-sh.de\\\/\",\"name\":\"Tex Clean Reinigung\",\"description\":\"Textilreinigung &amp; W&auml;scherei in Kiel &amp; Umgebung\",\"publisher\":{\"@id\":\"https:\\\/\\\/texclean-sh.de\\\/#organization\"},\"alternateName\":\"TexClean\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/texclean-sh.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/texclean-sh.de\\\/#organization\",\"name\":\"Tex Clean Reinigung\",\"url\":\"https:\\\/\\\/texclean-sh.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/texclean-sh.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/texclean-sh.de\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logo1.png\",\"contentUrl\":\"https:\\\/\\\/texclean-sh.de\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logo1.png\",\"width\":1000,\"height\":1000,\"caption\":\"Tex Clean Reinigung\"},\"image\":{\"@id\":\"https:\\\/\\\/texclean-sh.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tex.Clean.Reinigung\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mobile Textilreinigung & W\u00e4scherei in Kiel & Umgebung","description":"Mobile Textilreinigung & W\u00e4scherei in Kiel & Umgebung -Xpress Reinigung in 48 Stunden - Anzug Reinigung Kiel -Chemische Reinigung Abholservice","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/texclean-sh.de\/en\/","og_locale":"de_DE","og_type":"article","og_title":"Home","og_description":"Mobile Textilreinigung & W\u00e4scherei in Kiel & Umgebung -Xpress Reinigung in 48 Stunden - Anzug Reinigung Kiel -Chemische Reinigung Abholservice","og_url":"https:\/\/texclean-sh.de\/en\/","og_site_name":"Tex Clean","article_publisher":"https:\/\/www.facebook.com\/Tex.Clean.Reinigung","article_modified_time":"2025-05-13T09:43:50+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/texclean-sh.de\/wp-content\/uploads\/2025\/05\/Untitled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/texclean-sh.de\/","url":"https:\/\/texclean-sh.de\/","name":"Mobile Textilreinigung & W\u00e4scherei in Kiel & Umgebung","isPartOf":{"@id":"https:\/\/texclean-sh.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/texclean-sh.de\/#primaryimage"},"image":{"@id":"https:\/\/texclean-sh.de\/#primaryimage"},"thumbnailUrl":"https:\/\/texclean-sh.de\/wp-content\/uploads\/2025\/05\/Untitled-1.jpg","datePublished":"2023-12-02T06:55:45+00:00","dateModified":"2025-05-13T09:43:50+00:00","description":"Mobile Textilreinigung & W\u00e4scherei in Kiel & Umgebung -Xpress Reinigung in 48 Stunden - Anzug Reinigung Kiel -Chemische Reinigung Abholservice","breadcrumb":{"@id":"https:\/\/texclean-sh.de\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/texclean-sh.de\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/texclean-sh.de\/#primaryimage","url":"https:\/\/texclean-sh.de\/wp-content\/uploads\/2025\/05\/Untitled-1.jpg","contentUrl":"https:\/\/texclean-sh.de\/wp-content\/uploads\/2025\/05\/Untitled-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/texclean-sh.de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/texclean-sh.de\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/texclean-sh.de\/#website","url":"https:\/\/texclean-sh.de\/","name":"Tex Clean Reinigung","description":"Textilreinigung &amp; W&auml;scherei in Kiel &amp; Umgebung","publisher":{"@id":"https:\/\/texclean-sh.de\/#organization"},"alternateName":"TexClean","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/texclean-sh.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/texclean-sh.de\/#organization","name":"Tex Clean Reinigung","url":"https:\/\/texclean-sh.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/texclean-sh.de\/#\/schema\/logo\/image\/","url":"https:\/\/texclean-sh.de\/wp-content\/uploads\/2024\/02\/logo1.png","contentUrl":"https:\/\/texclean-sh.de\/wp-content\/uploads\/2024\/02\/logo1.png","width":1000,"height":1000,"caption":"Tex Clean Reinigung"},"image":{"@id":"https:\/\/texclean-sh.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tex.Clean.Reinigung"]}]}},"_links":{"self":[{"href":"https:\/\/texclean-sh.de\/en\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/texclean-sh.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/texclean-sh.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/texclean-sh.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/texclean-sh.de\/en\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":470,"href":"https:\/\/texclean-sh.de\/en\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":2094,"href":"https:\/\/texclean-sh.de\/en\/wp-json\/wp\/v2\/pages\/9\/revisions\/2094"}],"wp:attachment":[{"href":"https:\/\/texclean-sh.de\/en\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}